{"id":20238,"date":"2025-03-05T14:10:11","date_gmt":"2025-03-05T14:10:11","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-16\/"},"modified":"2025-03-05T14:21:58","modified_gmt":"2025-03-05T14:21:58","slug":"considerando-16","status":"publish","type":"page","link":"https:\/\/rgpd.com\/es\/reglamento-de-inteligencia-artificial\/preambulo\/considerando-16\/","title":{"rendered":"Considerando 16"},"content":{"rendered":"<p class=\"oj-normal\">El concepto de \u00abcategorizaci\u00f3n biom\u00e9trica\u00bb a\u00a0que hace referencia el presente Reglamento debe definirse como la inclusi\u00f3n de personas f\u00edsicas en categor\u00edas espec\u00edficas en funci\u00f3n de sus datos biom\u00e9tricos. Estas categor\u00edas espec\u00edficas pueden referirse a\u00a0aspectos como el sexo, la edad, el color del pelo, el color de los ojos, los tatuajes, los rasgos conductuales o\u00a0de la personalidad, la lengua, la religi\u00f3n, la pertenencia a\u00a0una minor\u00eda nacional o\u00a0la orientaci\u00f3n sexual o\u00a0pol\u00edtica. No se incluyen los sistemas de categorizaci\u00f3n biom\u00e9trica que sean una caracter\u00edstica meramente accesoria intr\u00ednsecamente vinculada a\u00a0otro servicio comercial, lo que significa que la caracter\u00edstica no puede utilizarse, por razones t\u00e9cnicas objetivas, sin el servicio principal y que la integraci\u00f3n de dicha caracter\u00edstica o\u00a0funcionalidad no es un medio para eludir la aplicabilidad de las normas del presente Reglamento. Por ejemplo, los filtros que clasifican las caracter\u00edsticas faciales o\u00a0corporales utilizados en los mercados en l\u00ednea podr\u00edan constituir una caracter\u00edstica accesoria de este tipo, ya que solo pueden utilizarse en relaci\u00f3n con el servicio principal, que consiste en vender un producto permitiendo al consumidor previsualizar c\u00f3mo le quedar\u00eda y ayudarlo a\u00a0tomar una decisi\u00f3n de compra. Los filtros utilizados en los servicios de redes sociales que clasifican las caracter\u00edsticas faciales o\u00a0corporales a\u00a0fin de que los usuarios puedan a\u00f1adir o\u00a0modificar im\u00e1genes o\u00a0v\u00eddeos tambi\u00e9n podr\u00edan considerarse una caracter\u00edstica accesoria, ya que dichos filtros no pueden utilizarse sin el servicio principal de las redes sociales, que consiste en compartir contenidos en l\u00ednea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concepto de \u00abcategorizaci\u00f3n biom\u00e9trica\u00bb a\u00a0que hace referencia el presente Reglamento debe definirse como la inclusi\u00f3n de personas f\u00edsicas en categor\u00edas espec\u00edficas en funci\u00f3n de sus datos biom\u00e9tricos. Estas categor\u00edas espec\u00edficas pueden referirse a\u00a0aspectos como el sexo, la edad, el color del pelo, el color de los ojos, los tatuajes, los rasgos conductuales o\u00a0de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20406,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20238","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/comments?post=20238"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20238\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20406"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/media?parent=20238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}