{"id":20254,"date":"2025-03-05T14:10:27","date_gmt":"2025-03-05T14:10:27","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-32\/"},"modified":"2025-03-05T14:22:15","modified_gmt":"2025-03-05T14:22:15","slug":"considerando-32","status":"publish","type":"page","link":"https:\/\/rgpd.com\/es\/reglamento-de-inteligencia-artificial\/preambulo\/considerando-32\/","title":{"rendered":"Considerando 32"},"content":{"rendered":"<p class=\"oj-normal\">El uso de sistemas de\u00a0IA para la identificaci\u00f3n biom\u00e9trica remota \u00aben tiempo real\u00bb de personas f\u00edsicas en espacios de acceso p\u00fablico con fines de garant\u00eda del cumplimiento del Derecho invade de forma especialmente grave los derechos y las libertades de las personas afectadas, en la medida en que puede afectar a\u00a0la vida privada de una gran parte de la poblaci\u00f3n, provocar la sensaci\u00f3n de estar bajo una vigilancia constante y disuadir indirectamente a\u00a0los ciudadanos de ejercer su libertad de reuni\u00f3n y otros derechos fundamentales. Las imprecisiones t\u00e9cnicas de los sistemas de\u00a0IA destinados a\u00a0la identificaci\u00f3n biom\u00e9trica remota de las personas f\u00edsicas pueden dar lugar a\u00a0resultados sesgados y tener efectos discriminatorios. Tales posibles resultados sesgados y efectos discriminatorios son especialmente pertinentes por lo que respecta a\u00a0la edad, la etnia, la raza, el sexo o\u00a0la discapacidad. Adem\u00e1s, la inmediatez de las consecuencias y las escasas oportunidades para realizar comprobaciones o\u00a0correcciones adicionales en relaci\u00f3n con el uso de sistemas que operan \u00aben tiempo real\u00bb acrecientan el riesgo que estos conllevan para los derechos y las libertades de las personas afectadas en el contexto de actividades de garant\u00eda del cumplimiento del Derecho, o\u00a0afectadas por estas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El uso de sistemas de\u00a0IA para la identificaci\u00f3n biom\u00e9trica remota \u00aben tiempo real\u00bb de personas f\u00edsicas en espacios de acceso p\u00fablico con fines de garant\u00eda del cumplimiento del Derecho invade de forma especialmente grave los derechos y las libertades de las personas afectadas, en la medida en que puede afectar a\u00a0la vida privada de una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20406,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20254","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/comments?post=20254"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20254\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20406"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/media?parent=20254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}