{"id":20306,"date":"2025-03-05T14:11:12","date_gmt":"2025-03-05T14:11:12","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-84\/"},"modified":"2025-03-05T14:23:01","modified_gmt":"2025-03-05T14:23:01","slug":"considerando-84","status":"publish","type":"page","link":"https:\/\/rgpd.com\/es\/reglamento-de-inteligencia-artificial\/preambulo\/considerando-84\/","title":{"rendered":"Considerando 84"},"content":{"rendered":"<p class=\"oj-normal\">Para garantizar la seguridad jur\u00eddica, es necesario aclarar que, en determinadas condiciones espec\u00edficas, debe considerarse proveedor de un sistema de\u00a0IA de alto riesgo a\u00a0cualquier distribuidor, importador, responsable del despliegue u\u00a0otro tercero que, por tanto, debe asumir todas las obligaciones pertinentes. Este ser\u00eda el caso si, por ejemplo, esa persona pone su nombre o\u00a0marca en un sistema de\u00a0IA de alto riesgo ya introducido en el mercado o\u00a0puesto en servicio, sin perjuicio de los acuerdos contractuales que estipulen otra distribuci\u00f3n de las obligaciones. Este tambi\u00e9n ser\u00eda el caso si dicha parte modifica sustancialmente un sistema de\u00a0IA de alto riesgo que ya se haya introducido en el mercado o\u00a0puesto en servicio de tal manera que el sistema modificado siga siendo un sistema de\u00a0IA de alto riesgo de conformidad con el presente Reglamento, o\u00a0si modifica la finalidad prevista de un sistema de\u00a0IA, como un sistema de\u00a0IA de uso general, que ya se haya introducido en el mercado o\u00a0puesto en servicio y que no est\u00e9 clasificado como sistema de alto riesgo, de tal manera que el sistema modificado pase a\u00a0ser un sistema de\u00a0IA de alto riesgo de conformidad con el presente Reglamento. Esas disposiciones deben aplicarse sin perjuicio de las disposiciones m\u00e1s espec\u00edficas establecidas en determinados actos legislativos de armonizaci\u00f3n de la Uni\u00f3n basados en el nuevo marco legislativo que se deben aplicar en conjunci\u00f3n con el presente Reglamento. Por ejemplo, el art\u00edculo\u00a016, apartado\u00a02, del Reglamento (UE)\u00a02017\/745, que establece que determinados cambios no deben considerarse modificaciones de un producto que puedan afectar al cumplimiento de los requisitos aplicables, debe seguir aplic\u00e1ndose a\u00a0los sistemas de\u00a0IA de alto riesgo que sean productos sanitarios en el sentido de dicho Reglamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para garantizar la seguridad jur\u00eddica, es necesario aclarar que, en determinadas condiciones espec\u00edficas, debe considerarse proveedor de un sistema de\u00a0IA de alto riesgo a\u00a0cualquier distribuidor, importador, responsable del despliegue u\u00a0otro tercero que, por tanto, debe asumir todas las obligaciones pertinentes. Este ser\u00eda el caso si, por ejemplo, esa persona pone su nombre o\u00a0marca en un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20406,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20306","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/comments?post=20306"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20306\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20406"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/media?parent=20306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}