{"id":20340,"date":"2025-03-05T14:11:24","date_gmt":"2025-03-05T14:11:24","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-118\/"},"modified":"2025-03-05T14:23:17","modified_gmt":"2025-03-05T14:23:17","slug":"considerando-118","status":"publish","type":"page","link":"https:\/\/rgpd.com\/es\/reglamento-de-inteligencia-artificial\/preambulo\/considerando-118\/","title":{"rendered":"Considerando 118"},"content":{"rendered":"<p class=\"oj-normal\">El presente Reglamento regula los sistemas de IA y modelos de\u00a0IA imponiendo determinados requisitos y obligaciones a\u00a0los agentes pertinentes del mercado que los introduzcan en el mercado, los pongan en servicio o\u00a0los utilicen en la Uni\u00f3n, complementando as\u00ed las obligaciones de los prestadores de servicios intermediarios que integren dichos sistemas o\u00a0modelos en sus servicios, regulados por el Reglamento (UE)\u00a02022\/2065. En la medida en que dichos sistemas o\u00a0modelos est\u00e9n integrados en plataformas en l\u00ednea de muy gran tama\u00f1o o\u00a0en motores de b\u00fasqueda en l\u00ednea de muy gran tama\u00f1o que hayan sido designados, est\u00e1n sujetos al marco de gesti\u00f3n de riesgos establecido en el Reglamento (UE)\u00a02022\/2065. Por consiguiente, debe presumirse que se han cumplido las obligaciones correspondientes del presente Reglamento a\u00a0menos que surjan riesgos sist\u00e9micos significativos no cubiertos por el Reglamento (UE)\u00a02022\/2065 y se detecten en dichos modelos. En este marco, los prestadores de plataformas en l\u00ednea de muy gran tama\u00f1o y de motores de b\u00fasqueda en l\u00ednea de muy gran tama\u00f1o est\u00e1n obligados a\u00a0evaluar los posibles riesgos sist\u00e9micos derivados del dise\u00f1o, el funcionamiento y el uso de sus servicios, incluido el modo en que el dise\u00f1o de los sistemas algor\u00edtmicos utilizados en el servicio puede contribuir a\u00a0dichos riesgos, as\u00ed como los riesgos sist\u00e9micos derivados de posibles usos indebidos. Dichos prestadores tambi\u00e9n est\u00e1n obligados a\u00a0adoptar las medidas de reducci\u00f3n de riesgos adecuadas respetando los derechos fundamentales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presente Reglamento regula los sistemas de IA y modelos de\u00a0IA imponiendo determinados requisitos y obligaciones a\u00a0los agentes pertinentes del mercado que los introduzcan en el mercado, los pongan en servicio o\u00a0los utilicen en la Uni\u00f3n, complementando as\u00ed las obligaciones de los prestadores de servicios intermediarios que integren dichos sistemas o\u00a0modelos en sus servicios, regulados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20406,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20340","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/comments?post=20340"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20340\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20406"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/media?parent=20340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}