{"id":20387,"date":"2025-03-05T14:11:59","date_gmt":"2025-03-05T14:11:59","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-165\/"},"modified":"2025-03-05T14:24:06","modified_gmt":"2025-03-05T14:24:06","slug":"considerando-165","status":"publish","type":"page","link":"https:\/\/rgpd.com\/es\/reglamento-de-inteligencia-artificial\/preambulo\/considerando-165\/","title":{"rendered":"Considerando 165"},"content":{"rendered":"<p class=\"oj-normal\">El desarrollo de sistemas de\u00a0IA que no sean sistemas de\u00a0IA de alto riesgo conforme a\u00a0los requisitos establecidos en el presente Reglamento puede dar lugar a\u00a0la adopci\u00f3n m\u00e1s amplia de una\u00a0IA \u00e9tica y fiable en la Uni\u00f3n. Se debe alentar a\u00a0los proveedores de sistemas de\u00a0IA que no son de alto riesgo a\u00a0crear c\u00f3digos de conducta, entre los que se incluyen los correspondientes mecanismos de gobernanza, destinados a\u00a0impulsar la aplicaci\u00f3n voluntaria de la totalidad o\u00a0parte de los requisitos aplicables a\u00a0los sistemas de\u00a0IA de alto riesgo, adaptados teniendo en cuenta la finalidad prevista de los sistemas y el menor riesgo planteado y teniendo en cuenta las soluciones t\u00e9cnicas disponibles y las mejores pr\u00e1cticas del sector, como las tarjetas de modelo y de datos Asimismo, se debe animar a\u00a0los proveedores y, en su caso, a\u00a0los responsables del despliegue de todos los sistemas de\u00a0IA, ya sean o\u00a0no de alto riesgo, y de los modelos de\u00a0IA, a\u00a0aplicar, con car\u00e1cter voluntario, requisitos adicionales relativos, por ejemplo, a\u00a0los elementos de las Directrices \u00e9ticas de la Uni\u00f3n para una\u00a0IA fiable, la sostenibilidad medioambiental, medidas de alfabetizaci\u00f3n en materia de\u00a0IA, la inclusividad y la diversidad en el dise\u00f1o y el desarrollo de los sistemas de\u00a0IA, lo que incluye tener en cuenta a\u00a0las personas vulnerables y la accesibilidad de las personas con discapacidad, la participaci\u00f3n de las partes interesadas, con la participaci\u00f3n, seg\u00fan proceda, de las partes interesadas pertinentes, como las organizaciones empresariales y de la sociedad civil, el mundo acad\u00e9mico, los organismos de investigaci\u00f3n, los sindicatos y las organizaciones de protecci\u00f3n de los consumidores, en el dise\u00f1o y el desarrollo de los sistemas de\u00a0IA, y la diversidad de los equipos de desarrollo, tambi\u00e9n por lo que respecta a\u00a0la paridad de g\u00e9nero. Para garantizar la efectividad de los c\u00f3digos de conducta voluntarios, estos deben basarse en objetivos claros e\u00a0indicadores clave del rendimiento que permitan medir la consecuci\u00f3n de dichos objetivos. Tambi\u00e9n deben desarrollarse de manera inclusiva, seg\u00fan proceda, con la participaci\u00f3n de las partes interesadas pertinentes, como las organizaciones empresariales y de la sociedad civil, el mundo acad\u00e9mico, los organismos de investigaci\u00f3n, los sindicatos y las organizaciones de protecci\u00f3n de los consumidores. La Comisi\u00f3n podr\u00eda formular iniciativas, tambi\u00e9n de car\u00e1cter sectorial, encaminadas a\u00a0facilitar la disminuci\u00f3n de los obst\u00e1culos t\u00e9cnicos que dificultan el intercambio transfronterizo de datos para el desarrollo de la\u00a0IA, tambi\u00e9n en relaci\u00f3n con la infraestructura de acceso a\u00a0los datos y la interoperabilidad sem\u00e1ntica y t\u00e9cnica de distintos tipos de datos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El desarrollo de sistemas de\u00a0IA que no sean sistemas de\u00a0IA de alto riesgo conforme a\u00a0los requisitos establecidos en el presente Reglamento puede dar lugar a\u00a0la adopci\u00f3n m\u00e1s amplia de una\u00a0IA \u00e9tica y fiable en la Uni\u00f3n. Se debe alentar a\u00a0los proveedores de sistemas de\u00a0IA que no son de alto riesgo a\u00a0crear c\u00f3digos de conducta, entre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20406,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20387","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/comments?post=20387"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20387\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/pages\/20406"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/es\/wp-json\/wp\/v2\/media?parent=20387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}