{"id":19887,"date":"2025-03-05T14:10:27","date_gmt":"2025-03-05T14:10:27","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-25\/"},"modified":"2025-03-05T14:14:41","modified_gmt":"2025-03-05T14:14:41","slug":"considerant-25","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-25\/","title":{"rendered":"Consid\u00e9rant 25"},"content":{"rendered":"<p class=\"oj-normal\">Le pr\u00e9sent r\u00e8glement devrait soutenir l\u2019innovation et respecter la libert\u00e9 scientifique et ne devrait pas compromettre les activit\u00e9s de recherche et de d\u00e9veloppement. Il est donc n\u00e9cessaire d\u2019exclure de son champ d\u2019application les syst\u00e8mes et mod\u00e8les d\u2019IA sp\u00e9cifiquement d\u00e9velopp\u00e9s et mis en service aux seules fins de la recherche et du d\u00e9veloppement scientifiques. En outre, il est n\u00e9cessaire de veiller \u00e0\u00a0ce que le pr\u00e9sent r\u00e8glement n\u2019affecte pas autrement les activit\u00e9s de recherche et de d\u00e9veloppement scientifiques relatives aux syst\u00e8mes ou mod\u00e8les d\u2019IA avant leur mise sur le march\u00e9 ou leur mise en service. En ce qui concerne les activit\u00e9s de recherche, d\u2019essai et de d\u00e9veloppement ax\u00e9es sur les produits, relatives aux syst\u00e8mes ou mod\u00e8les d\u2019IA, les dispositions du pr\u00e9sent r\u00e8glement ne devraient pas non plus s\u2019appliquer avant la mise en service ou la mise sur le march\u00e9 de ces syst\u00e8mes et mod\u00e8les. Cette exclusion est sans pr\u00e9judice de l\u2019obligation de se conformer au pr\u00e9sent r\u00e8glement lorsqu\u2019un syst\u00e8me d\u2019IA relevant du champ d\u2019application du pr\u00e9sent r\u00e8glement est mis sur le march\u00e9 ou mis en service \u00e0\u00a0la suite de cette activit\u00e9 de recherche et de d\u00e9veloppement, et sans pr\u00e9judice de l\u2019application des dispositions relatives aux bacs \u00e0\u00a0sable r\u00e9glementaires de l\u2019IA et aux essais en conditions r\u00e9elles. En outre, sans pr\u00e9judice de l\u2019exclusion des syst\u00e8mes d\u2019IA sp\u00e9cifiquement d\u00e9velopp\u00e9s et mis en service aux seules fins de la recherche et du d\u00e9veloppement scientifiques, tout autre syst\u00e8me d\u2019IA susceptible d\u2019\u00eatre utilis\u00e9 pour mener une activit\u00e9 de recherche et de d\u00e9veloppement devrait rester soumis aux dispositions du pr\u00e9sent r\u00e8glement. En tout \u00e9tat de cause, toute activit\u00e9 de recherche et de d\u00e9veloppement devrait \u00eatre men\u00e9e conform\u00e9ment \u00e0\u00a0des normes \u00e9thiques et professionnelles reconnues en mati\u00e8re de recherche scientifique et dans le respect du droit de l\u2019Union applicable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sent r\u00e8glement devrait soutenir l\u2019innovation et respecter la libert\u00e9 scientifique et ne devrait pas compromettre les activit\u00e9s de recherche et de d\u00e9veloppement. Il est donc n\u00e9cessaire d\u2019exclure de son champ d\u2019application les syst\u00e8mes et mod\u00e8les d\u2019IA sp\u00e9cifiquement d\u00e9velopp\u00e9s et mis en service aux seules fins de la recherche et du d\u00e9veloppement scientifiques. En outre, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-19887","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=19887"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19887\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=19887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}