{"id":19891,"date":"2025-03-05T14:10:27","date_gmt":"2025-03-05T14:10:27","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-29\/"},"modified":"2025-03-05T14:14:41","modified_gmt":"2025-03-05T14:14:41","slug":"considerant-29","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-29\/","title":{"rendered":"Consid\u00e9rant 29"},"content":{"rendered":"<p class=\"oj-normal\">Des techniques de manipulation fond\u00e9es sur l\u2019IA peuvent \u00eatre utilis\u00e9es pour persuader des personnes d\u2019adopter des comportements ind\u00e9sirables ou pour les tromper en les poussant \u00e0\u00a0prendre des d\u00e9cisions d\u2019une mani\u00e8re qui met \u00e0\u00a0mal et compromet leur autonomie, leur libre arbitre et leur libert\u00e9 de choix. La mise sur le march\u00e9, la mise en service ou l\u2019utilisation de certains syst\u00e8mes d\u2019IA ayant pour objectif ou pour effet d\u2019alt\u00e9rer substantiellement les comportements humains, avec le risque de causer des dommages importants, en particulier d\u2019avoir des incidences suffisamment importantes sur la sant\u00e9 physique ou psychologique ou sur les int\u00e9r\u00eats financiers, sont particuli\u00e8rement dangereuses et devraient d\u00e8s lors \u00eatre interdites. Ces syst\u00e8mes d\u2019IA font intervenir des composants subliminaux, tels que des stimuli sonores, visuels ou vid\u00e9o que l\u2019individu ne peut percevoir, \u00e9tant donn\u00e9 que ces stimuli \u00e9chappent \u00e0\u00a0la perception humaine, ou d\u2019autres techniques manipulatrices ou trompeuses qui mettent \u00e0\u00a0mal ou alt\u00e8rent l\u2019autonomie de la personne, son libre arbitre ou sa libert\u00e9 de choix de telle sorte que l\u2019individu n\u2019est pas conscient de ces techniques ou, \u00e0\u00a0supposer qu\u2019il le soit, sans qu\u2019il puisse \u00e9chapper \u00e0\u00a0la duperie ni opposer une r\u00e9sistance ou un contr\u00f4le auxdites techniques. Cela pourrait \u00eatre facilit\u00e9, par exemple, par des interfaces cerveau-machine ou par la r\u00e9alit\u00e9 virtuelle \u00e9tant donn\u00e9 qu\u2019elles permettent d\u2019avoir plus de contr\u00f4le sur les stimuli qui sont pr\u00e9sent\u00e9s aux personnes, dans la mesure o\u00f9 elles peuvent en alt\u00e9rer sensiblement le comportement d\u2019une mani\u00e8re tr\u00e8s nocive. En outre, des syst\u00e8mes d\u2019IA peuvent \u00e9galement exploiter les vuln\u00e9rabilit\u00e9s d\u2019une personne ou d\u2019un groupe particulier de personnes en raison de leur \u00e2ge, d\u2019un handicap au sens de la directive (UE) 2019\/882 du Parlement europ\u00e9en et du Conseil\u00a0<a href=\"#ntr16-L_202401689FR.000101-E0016\" id=\"ntc16-L_202401689FR.000101-E0016\">(<span class=\"oj-super oj-note-tag\">16<\/span>)<\/a>, ou d\u2019une situation sociale ou \u00e9conomique sp\u00e9cifique susceptible de rendre ces personnes plus vuln\u00e9rables \u00e0\u00a0l\u2019exploitation, telles que les personnes vivant dans une extr\u00eame pauvret\u00e9 ou appartenant \u00e0\u00a0des minorit\u00e9s ethniques ou religieuses. De tels syst\u00e8mes d\u2019IA peuvent \u00eatre mis sur le march\u00e9, mis en service ou utilis\u00e9s avec pour objectif ou pour effet d\u2019alt\u00e9rer substantiellement le comportement d\u2019une personne d\u2019une mani\u00e8re qui cause ou est raisonnablement susceptible de causer un pr\u00e9judice important \u00e0\u00a0cette personne ou \u00e0\u00a0une autre personne ou \u00e0\u00a0des groupes de personnes, y compris des dommages susceptibles de s\u2019accumuler au fil du temps, et il y a\u00a0lieu, par cons\u00e9quent, de les interdire. Il peut s\u2019av\u00e9rer impossible de pr\u00e9sumer l\u2019existence d\u2019une intention d\u2019alt\u00e9rer le comportement lorsque cette alt\u00e9ration r\u00e9sulte de facteurs externes au syst\u00e8me d\u2019IA qui \u00e9chappent au contr\u00f4le du fournisseur ou du d\u00e9ployeur, \u00e0\u00a0savoir de facteurs qui ne peuvent \u00eatre raisonnablement pr\u00e9visibles, et partant, ne peuvent \u00eatre att\u00e9nu\u00e9s par le fournisseur ou le d\u00e9ployeur du syst\u00e8me d\u2019IA. En tout \u00e9tat de cause, il n\u2019est pas n\u00e9cessaire que le fournisseur ou le d\u00e9ployeur ait l\u2019intention de causer un pr\u00e9judice important, du moment que ce pr\u00e9judice r\u00e9sulte de pratiques de manipulation ou d\u2019exploitation reposant sur l\u2019IA. Les interdictions de telles pratiques en mati\u00e8re d\u2019IA compl\u00e8tent les dispositions de la directive 2005\/29\/CE du Parlement europ\u00e9en et du Conseil\u00a0<a href=\"#ntr17-L_202401689FR.000101-E0017\" id=\"ntc17-L_202401689FR.000101-E0017\">(<span class=\"oj-super oj-note-tag\">17<\/span>)<\/a>, notamment concernant le fait que les pratiques commerciales d\u00e9loyales entra\u00eenant des pr\u00e9judices \u00e9conomiques ou financiers pour les consommateurs sont interdites en toutes circonstances, qu\u2019elles soient mises en place au moyen de syst\u00e8mes d\u2019IA ou autrement. Les interdictions des pratiques de manipulation et d\u2019exploitation pr\u00e9vues par le pr\u00e9sent r\u00e8glement ne devraient pas affecter les pratiques licites dans le cadre de traitements m\u00e9dicaux tels que le traitement psychologique d\u2019une maladie mentale ou la r\u00e9\u00e9ducation physique, lorsque ces pratiques sont effectu\u00e9es conform\u00e9ment \u00e0\u00a0la l\u00e9gislation applicable et aux normes m\u00e9dicales, comme le consentement explicite des personnes ou de leurs repr\u00e9sentants l\u00e9gaux. En outre, les pratiques commerciales courantes et l\u00e9gitimes, par exemple dans le domaine de la publicit\u00e9, qui respectent le droit applicable ne devraient pas, en soi, \u00eatre consid\u00e9r\u00e9es comme constituant des pratiques de manipulation pr\u00e9judiciables reposant sur l\u2019IA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des techniques de manipulation fond\u00e9es sur l\u2019IA peuvent \u00eatre utilis\u00e9es pour persuader des personnes d\u2019adopter des comportements ind\u00e9sirables ou pour les tromper en les poussant \u00e0\u00a0prendre des d\u00e9cisions d\u2019une mani\u00e8re qui met \u00e0\u00a0mal et compromet leur autonomie, leur libre arbitre et leur libert\u00e9 de choix. La mise sur le march\u00e9, la mise en service ou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-19891","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=19891"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19891\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=19891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}