{"id":19905,"date":"2025-03-05T14:10:42","date_gmt":"2025-03-05T14:10:42","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-43\/"},"modified":"2025-03-05T14:14:53","modified_gmt":"2025-03-05T14:14:53","slug":"considerant-43","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-43\/","title":{"rendered":"Consid\u00e9rant 43"},"content":{"rendered":"<p class=\"oj-normal\">Il y a\u00a0lieu d\u2019interdire la mise sur le march\u00e9, la mise en service \u00e0\u00a0cette fin sp\u00e9cifique ou l\u2019utilisation de syst\u00e8mes d\u2019IA qui cr\u00e9ent ou d\u00e9veloppent des bases de donn\u00e9es de reconnaissance faciale par le moissonnage non cibl\u00e9 d\u2019images faciales provenant de l\u2019internet ou de la vid\u00e9osurveillance, parce que cette pratique ne fait qu\u2019accentuer le sentiment de surveillance de masse et peut entra\u00eener des violations flagrantes des droits fondamentaux, y compris du droit au respect de la vie priv\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a\u00a0lieu d\u2019interdire la mise sur le march\u00e9, la mise en service \u00e0\u00a0cette fin sp\u00e9cifique ou l\u2019utilisation de syst\u00e8mes d\u2019IA qui cr\u00e9ent ou d\u00e9veloppent des bases de donn\u00e9es de reconnaissance faciale par le moissonnage non cibl\u00e9 d\u2019images faciales provenant de l\u2019internet ou de la vid\u00e9osurveillance, parce que cette pratique ne fait qu\u2019accentuer le sentiment [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-19905","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=19905"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19905\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=19905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}