{"id":19924,"date":"2025-03-05T14:10:57","date_gmt":"2025-03-05T14:10:57","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-62\/"},"modified":"2025-03-05T14:15:11","modified_gmt":"2025-03-05T14:15:11","slug":"considerant-62","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-62\/","title":{"rendered":"Consid\u00e9rant 62"},"content":{"rendered":"<p class=\"oj-normal\">Sans pr\u00e9judice des r\u00e8gles pr\u00e9vues dans le r\u00e8glement (UE) 2024\/900 du Parlement europ\u00e9en et du Conseil\u00a0<a href=\"#ntr34-L_202401689FR.000101-E0034\" id=\"ntc34-L_202401689FR.000101-E0034\">(<span class=\"oj-super oj-note-tag\">34<\/span>)<\/a>, et afin de faire face aux risques d\u2019ing\u00e9rence ext\u00e9rieure indue dans le droit de vote consacr\u00e9 \u00e0\u00a0l\u2019article\u00a039 de la Charte et d\u2019effets n\u00e9gatifs sur la d\u00e9mocratie et l\u2019\u00e9tat de droit, les syst\u00e8mes d\u2019IA destin\u00e9s \u00e0\u00a0\u00eatre utilis\u00e9s pour influencer le r\u00e9sultat d\u2019une \u00e9lection ou d\u2019un r\u00e9f\u00e9rendum ou le comportement \u00e9lectoral de personnes physiques dans l\u2019exercice de leur vote lors d\u2019\u00e9lections ou de r\u00e9f\u00e9rendums devraient \u00eatre class\u00e9s comme \u00e9tant \u00e0\u00a0haut risque, \u00e0\u00a0l\u2019exception des syst\u00e8mes d\u2019IA dont les sorties ne touchent pas directement les personnes physiques, tels que les outils utilis\u00e9s pour organiser, optimiser et structurer les campagnes politiques d\u2019un point de vue administratif et logistique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sans pr\u00e9judice des r\u00e8gles pr\u00e9vues dans le r\u00e8glement (UE) 2024\/900 du Parlement europ\u00e9en et du Conseil\u00a0(34), et afin de faire face aux risques d\u2019ing\u00e9rence ext\u00e9rieure indue dans le droit de vote consacr\u00e9 \u00e0\u00a0l\u2019article\u00a039 de la Charte et d\u2019effets n\u00e9gatifs sur la d\u00e9mocratie et l\u2019\u00e9tat de droit, les syst\u00e8mes d\u2019IA destin\u00e9s \u00e0\u00a0\u00eatre utilis\u00e9s pour influencer le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-19924","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=19924"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19924\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=19924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}