{"id":19955,"date":"2025-03-05T14:11:12","date_gmt":"2025-03-05T14:11:12","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-93\/"},"modified":"2025-03-05T14:15:24","modified_gmt":"2025-03-05T14:15:24","slug":"considerant-93","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-93\/","title":{"rendered":"Consid\u00e9rant 93"},"content":{"rendered":"<p class=\"oj-normal\">Si des risques li\u00e9s aux syst\u00e8mes d\u2019IA peuvent d\u00e9couler de la mani\u00e8re dont ces syst\u00e8mes sont con\u00e7us, ils peuvent \u00e9galement provenir de la mani\u00e8re dont ces syst\u00e8mes d\u2019IA sont utilis\u00e9s. Les d\u00e9ployeurs de syst\u00e8mes d\u2019IA \u00e0\u00a0haut risque jouent donc un r\u00f4le essentiel pour ce qui est de garantir la protection des droits fondamentaux, en compl\u00e9tant les obligations du fournisseur lors du d\u00e9veloppement du syst\u00e8me d\u2019IA. Les d\u00e9ployeurs sont les mieux plac\u00e9s pour comprendre comment le syst\u00e8me d\u2019IA \u00e0\u00a0haut risque sera utilis\u00e9 concr\u00e8tement et peuvent donc identifier les risques importants potentiels qui n\u2019\u00e9taient pas pr\u00e9vus au cours de la phase de d\u00e9veloppement, en raison d\u2019une connaissance plus pr\u00e9cise du contexte d\u2019utilisation et des personnes ou groupes de personnes susceptibles d\u2019\u00eatre concern\u00e9s, y compris les groupes vuln\u00e9rables. Les d\u00e9ployeurs de syst\u00e8mes d\u2019IA \u00e0\u00a0haut risque \u00e9num\u00e9r\u00e9s dans une annexe du pr\u00e9sent r\u00e8glement contribuent \u00e9galement de fa\u00e7on essentielle \u00e0\u00a0informer les personnes physiques et devraient, lorsqu\u2019ils prennent des d\u00e9cisions ou facilitent la prise de d\u00e9cisions concernant des personnes physiques, selon le cas, informer lesdites personnes physiques qu\u2019elles sont soumises \u00e0\u00a0l\u2019utilisation du syst\u00e8me d\u2019IA \u00e0\u00a0haut risque. Cette information devrait comprendre la destination du syst\u00e8me et le type de d\u00e9cisions prises. Les d\u00e9ployeurs devraient aussi informer les personnes physiques de leur droit \u00e0\u00a0une explication pr\u00e9vu par le pr\u00e9sent r\u00e8glement. En ce qui concerne les syst\u00e8mes d\u2019IA \u00e0\u00a0haut risque utilis\u00e9s \u00e0\u00a0des fins r\u00e9pressives, cette obligation devrait \u00eatre mise en \u0153uvre conform\u00e9ment \u00e0\u00a0l\u2019article\u00a013 de la directive (UE) 2016\/680.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si des risques li\u00e9s aux syst\u00e8mes d\u2019IA peuvent d\u00e9couler de la mani\u00e8re dont ces syst\u00e8mes sont con\u00e7us, ils peuvent \u00e9galement provenir de la mani\u00e8re dont ces syst\u00e8mes d\u2019IA sont utilis\u00e9s. Les d\u00e9ployeurs de syst\u00e8mes d\u2019IA \u00e0\u00a0haut risque jouent donc un r\u00f4le essentiel pour ce qui est de garantir la protection des droits fondamentaux, en compl\u00e9tant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-19955","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=19955"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19955\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=19955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}