{"id":19971,"date":"2025-03-05T14:11:24","date_gmt":"2025-03-05T14:11:24","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-109\/"},"modified":"2025-03-05T14:15:38","modified_gmt":"2025-03-05T14:15:38","slug":"considerant-109","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-109\/","title":{"rendered":"Consid\u00e9rant 109"},"content":{"rendered":"<p class=\"oj-normal\">Le respect des obligations applicables aux fournisseurs de mod\u00e8les d\u2019IA \u00e0\u00a0usage g\u00e9n\u00e9ral devrait correspondre et \u00eatre proportionn\u00e9 au type de fournisseur de mod\u00e8les, excluant la n\u00e9cessit\u00e9 de se conformer pour les personnes qui d\u00e9veloppent ou utilisent des mod\u00e8les \u00e0\u00a0des fins non professionnelles ou de recherche scientifique, lesquelles devraient n\u00e9anmoins \u00eatre encourag\u00e9es \u00e0\u00a0se conformer volontairement \u00e0\u00a0ces exigences. Sans pr\u00e9judice de la l\u00e9gislation de l\u2019Union sur le droit d\u2019auteur, le respect de ces obligations devrait tenir d\u00fbment compte de la taille du fournisseur et permettre aux PME, y compris aux jeunes pousses, de recourir \u00e0\u00a0des m\u00e9thodes simplifi\u00e9es de mise en conformit\u00e9 qui ne devraient pas repr\u00e9senter un co\u00fbt excessif et d\u00e9courager l\u2019utilisation de tels mod\u00e8les. En cas de modification ou de r\u00e9glage fin d\u2019un mod\u00e8le, les obligations incombant aux fournisseurs de mod\u00e8les d\u2019IA \u00e0\u00a0usage g\u00e9n\u00e9ral devraient se limiter \u00e0\u00a0cette modification ou \u00e0\u00a0ce r\u00e9glage fin, par exemple en compl\u00e9tant la documentation technique existante avec des informations sur les modifications, y compris les nouvelles sources de donn\u00e9es d\u2019entra\u00eenement, aux fins de conformit\u00e9 avec les obligations relatives \u00e0\u00a0la cha\u00eene de valeur pr\u00e9vues par le pr\u00e9sent r\u00e8glement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le respect des obligations applicables aux fournisseurs de mod\u00e8les d\u2019IA \u00e0\u00a0usage g\u00e9n\u00e9ral devrait correspondre et \u00eatre proportionn\u00e9 au type de fournisseur de mod\u00e8les, excluant la n\u00e9cessit\u00e9 de se conformer pour les personnes qui d\u00e9veloppent ou utilisent des mod\u00e8les \u00e0\u00a0des fins non professionnelles ou de recherche scientifique, lesquelles devraient n\u00e9anmoins \u00eatre encourag\u00e9es \u00e0\u00a0se conformer volontairement \u00e0\u00a0ces [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-19971","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=19971"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19971\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=19971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}