{"id":19988,"date":"2025-03-05T14:11:35","date_gmt":"2025-03-05T14:11:35","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-126\/"},"modified":"2025-03-05T14:15:52","modified_gmt":"2025-03-05T14:15:52","slug":"considerant-126","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-126\/","title":{"rendered":"Consid\u00e9rant 126"},"content":{"rendered":"<p class=\"oj-normal\">Afin de proc\u00e9der \u00e0\u00a0des \u00e9valuations de la conformit\u00e9 par un tiers lorsque cela est n\u00e9cessaire, les organismes notifi\u00e9s devraient \u00eatre notifi\u00e9s en vertu du pr\u00e9sent r\u00e8glement par les autorit\u00e9s nationales comp\u00e9tentes, sous r\u00e9serve qu\u2019ils satisfassent \u00e0\u00a0un ensemble d\u2019exigences portant en particulier sur leur ind\u00e9pendance, leur comp\u00e9tence, l\u2019absence de conflits d\u2019int\u00e9r\u00eats et les exigences appropri\u00e9es en mati\u00e8re de cybers\u00e9curit\u00e9. La notification de ces organismes devrait \u00eatre envoy\u00e9e par les autorit\u00e9s nationales comp\u00e9tentes \u00e0\u00a0la Commission et aux autres \u00c9tats membres \u00e0\u00a0l\u2019aide de l\u2019outil de notification \u00e9lectronique mis au point et g\u00e9r\u00e9 par la Commission, conform\u00e9ment \u00e0\u00a0l\u2019annexe\u00a0I, article\u00a0R23, de la d\u00e9cision n<span class=\"oj-super\">o<\/span>\u00a0768\/2008\/CE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afin de proc\u00e9der \u00e0\u00a0des \u00e9valuations de la conformit\u00e9 par un tiers lorsque cela est n\u00e9cessaire, les organismes notifi\u00e9s devraient \u00eatre notifi\u00e9s en vertu du pr\u00e9sent r\u00e8glement par les autorit\u00e9s nationales comp\u00e9tentes, sous r\u00e9serve qu\u2019ils satisfassent \u00e0\u00a0un ensemble d\u2019exigences portant en particulier sur leur ind\u00e9pendance, leur comp\u00e9tence, l\u2019absence de conflits d\u2019int\u00e9r\u00eats et les exigences appropri\u00e9es en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-19988","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=19988"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/19988\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=19988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}