{"id":20010,"date":"2025-03-05T14:11:47","date_gmt":"2025-03-05T14:11:47","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-148\/"},"modified":"2025-03-05T14:16:07","modified_gmt":"2025-03-05T14:16:07","slug":"considerant-148","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-148\/","title":{"rendered":"Consid\u00e9rant 148"},"content":{"rendered":"<p class=\"oj-normal\">Le pr\u00e9sent r\u00e8glement devrait \u00e9tablir un cadre de gouvernance qui permette \u00e0\u00a0la fois de coordonner et de soutenir l\u2019application du pr\u00e9sent r\u00e8glement au niveau national, ainsi que de renforcer les capacit\u00e9s au niveau de l\u2019Union et d\u2019int\u00e9grer les parties prenantes dans le domaine de l\u2019IA. La mise en \u0153uvre et le contr\u00f4le de l\u2019application effectifs du pr\u00e9sent r\u00e8glement requi\u00e8rent un cadre de gouvernance qui permette de coordonner et de renforcer l\u2019expertise centrale au niveau de l\u2019Union. Le Bureau de l\u2019IA a\u00a0\u00e9t\u00e9 cr\u00e9\u00e9 par voie d\u2019une d\u00e9cision de la Commission\u00a0<a href=\"#ntr45-L_202401689FR.000101-E0045\" id=\"ntc45-L_202401689FR.000101-E0045\">(<span class=\"oj-super oj-note-tag\">45<\/span>)<\/a> et a\u00a0pour mission d\u2019approfondir l\u2019expertise et de renforcer les capacit\u00e9s de l\u2019Union dans le domaine de l\u2019IA ainsi que de contribuer \u00e0\u00a0la mise en \u0153uvre de la l\u00e9gislation de l\u2019Union sur l\u2019IA. Les \u00c9tats membres devraient faciliter l\u2019accomplissement des missions du Bureau de l\u2019IA en vue de soutenir le d\u00e9veloppement de l\u2019expertise de l\u2019Union et des capacit\u00e9s au niveau de l\u2019Union et de renforcer le fonctionnement du march\u00e9 unique num\u00e9rique. En outre, il convient d\u2019\u00e9tablir un Comit\u00e9 IA compos\u00e9 de repr\u00e9sentants des \u00c9tats membres, un groupe scientifique visant \u00e0\u00a0int\u00e9grer la communaut\u00e9 scientifique et un forum consultatif visant \u00e0\u00a0recueillir les contributions des parties concern\u00e9es en vue de la mise en \u0153uvre du pr\u00e9sent r\u00e8glement, au niveau de l\u2019Union et au niveau national. Le d\u00e9veloppement de l\u2019expertise et des capacit\u00e9s de l\u2019Union devrait \u00e9galement consister \u00e0\u00a0utiliser les ressources et l\u2019expertise existantes, en particulier gr\u00e2ce \u00e0\u00a0des synergies avec les structures \u00e9tablies dans le contexte de l\u2019application au niveau de l\u2019Union d\u2019autres dispositions l\u00e9gislatives et \u00e0\u00a0des synergies avec des initiatives connexes au niveau de l\u2019Union, telles que l\u2019entreprise commune EuroHPC et les installations de mise \u00e0\u00a0l\u2019essai de l\u2019IA et d\u2019exp\u00e9rimentations relevant du programme pour une Europe num\u00e9rique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sent r\u00e8glement devrait \u00e9tablir un cadre de gouvernance qui permette \u00e0\u00a0la fois de coordonner et de soutenir l\u2019application du pr\u00e9sent r\u00e8glement au niveau national, ainsi que de renforcer les capacit\u00e9s au niveau de l\u2019Union et d\u2019int\u00e9grer les parties prenantes dans le domaine de l\u2019IA. La mise en \u0153uvre et le contr\u00f4le de l\u2019application effectifs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20010","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=20010"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20010\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=20010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}