{"id":20031,"date":"2025-03-05T14:11:59","date_gmt":"2025-03-05T14:11:59","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerant-169\/"},"modified":"2025-03-05T14:16:22","modified_gmt":"2025-03-05T14:16:22","slug":"considerant-169","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/preambule\/considerant-169\/","title":{"rendered":"Consid\u00e9rant 169"},"content":{"rendered":"<p class=\"oj-normal\">Le respect des obligations incombant aux fournisseurs de mod\u00e8les d\u2019IA \u00e0\u00a0usage g\u00e9n\u00e9ral au titre du pr\u00e9sent r\u00e8glement devrait pouvoir \u00eatre impos\u00e9, entre autres, au moyen d\u2019amendes. \u00c0 cette fin, des niveaux appropri\u00e9s d\u2019amendes devraient \u00e9galement \u00eatre fix\u00e9s pour les infractions \u00e0\u00a0ces obligations, y compris le non-respect de mesures demand\u00e9es par la Commission en vertu au pr\u00e9sent r\u00e8glement, sous r\u00e9serve de d\u00e9lais de prescription appropri\u00e9s conform\u00e9ment du principe de proportionnalit\u00e9. Toutes les d\u00e9cisions prises par la Commission au titre du pr\u00e9sent r\u00e8glement sont soumises au contr\u00f4le de la Cour de justice de l\u2019Union europ\u00e9enne conform\u00e9ment au trait\u00e9 sur le fonctionnement de l\u2019Union europ\u00e9enne, y compris la comp\u00e9tence de pleine juridiction de la Cour de justice en ce qui concerne les sanctions en application de l\u2019article\u00a0261 du trait\u00e9 sur le fonctionnement de l\u2019Union europ\u00e9enne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le respect des obligations incombant aux fournisseurs de mod\u00e8les d\u2019IA \u00e0\u00a0usage g\u00e9n\u00e9ral au titre du pr\u00e9sent r\u00e8glement devrait pouvoir \u00eatre impos\u00e9, entre autres, au moyen d\u2019amendes. \u00c0 cette fin, des niveaux appropri\u00e9s d\u2019amendes devraient \u00e9galement \u00eatre fix\u00e9s pour les infractions \u00e0\u00a0ces obligations, y compris le non-respect de mesures demand\u00e9es par la Commission en vertu au [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20404,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20031","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=20031"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20031\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/20404"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=20031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}