{"id":2019,"date":"2022-03-21T14:39:54","date_gmt":"2022-03-21T14:39:54","guid":{"rendered":"https:\/\/rgpd.com\/chapitre-3-droits-de-la-personne-concernee\/article-17-droit-a-leffacement-droit-a-loubli\/"},"modified":"2024-06-04T10:02:43","modified_gmt":"2024-06-04T10:02:43","slug":"article-17-droit-a-leffacement-droit-a-loubli","status":"publish","type":"page","link":"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-17-droit-a-leffacement-droit-a-loubli\/","title":{"rendered":"Article 17: Droit \u00e0 l&rsquo;effacement (\u00abdroit \u00e0 l&rsquo;oubli\u00bb)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2019\" class=\"elementor elementor-2019 elementor-723\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6ce793 e-con-full e-flex e-con e-parent\" data-id=\"a6ce793\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f29695d e-con-full e-flex e-con e-child\" data-id=\"f29695d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f2cb6b elementor-widget elementor-widget-template\" data-id=\"0f2cb6b\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2399\" class=\"elementor elementor-2399 elementor-123\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5527dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5527dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a49473\" data-id=\"2a49473\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dedea12 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"dedea12\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8875826\" data-id=\"8875826\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ae4909 elementor-hidden-tablet elementor-hidden-mobile custom-nav elementor-widget elementor-widget-nav-menu\" data-id=\"7ae4909\" data-element_type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;dropdown&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7ae4909\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-30163\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">GDPR | AI Act | NIS2<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30164\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">RGPD<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30165\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-1-dispositions-generales\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 1: Dispositions g\u00e9n\u00e9rales<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30166\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-1-dispositions-generales\/article-1-objet-et-objectifs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 1: Objet et objectifs<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30167\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-1-dispositions-generales\/article-2-champ-dapplication-materiel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 2: Champ d&rsquo;application mat\u00e9riel<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30194\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-1-dispositions-generales\/article-3-champ-dapplication-territorial\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 3: Champ d&rsquo;application territorial<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30195\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-1-dispositions-generales\/article-4-definitions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 4: D\u00e9finitions<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30196\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 2: Principes<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30197\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/article-5-principes-relatifs-au-traitement-des-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 5: Principes relatifs au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30198\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/article-6-liceite-du-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 6: Lic\u00e9it\u00e9 du traitement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30199\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/article-7-conditions-applicables-au-consentement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 7: Conditions applicables au consentement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30200\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/article-8-conditions-applicables-au-consentement-des-enfants-en-ce-qui-concerne-les-services-de-la-societe-de-linformation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 8: Conditions applicables au consentement des enfants en ce qui concerne les services de la soci\u00e9t\u00e9 de l&rsquo;information<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30201\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/article-9-traitement-portant-sur-des-categories-particulieres-de-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 9: Traitement portant sur des cat\u00e9gories particuli\u00e8res de donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30202\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/article-10-traitement-des-donnees-a-caractere-personnel-relatives-aux-condamnations-penales-et-aux-infractions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 10: Traitement des donn\u00e9es \u00e0 caract\u00e8re personnel relatives aux condamnations p\u00e9nales et aux infractions<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30203\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-2-principes\/article-11-traitement-ne-necessitant-pas-lidentification\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 11: Traitement ne n\u00e9cessitant pas l&rsquo;identification<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30204\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 3: Droits de la personne concern\u00e9e<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30205\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-12-transparence-des-informations-et-des-communications-et-modalites-de-lexercice-des-droits-de-la-personne-concernee\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 12: Transparence des informations et des communications et modalit\u00e9s de l&rsquo;exercice des droits de la personne concern\u00e9e<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30206\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-13-informations-a-fournir-lorsque-des-donnees-a-caractere-personnel-sont-collectees-aupres-de-la-personne-concernee\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 13: Informations \u00e0 fournir lorsque des donn\u00e9es \u00e0 caract\u00e8re personnel sont collect\u00e9es aupr\u00e8s de la personne concern\u00e9e<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30207\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-14-informations-a-fournir-lorsque-les-donnees-a-caractere-personnel-nont-pas-ete-collectees-aupres-de-la-personne-concernee\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 14: Informations \u00e0 fournir lorsque les donn\u00e9es \u00e0 caract\u00e8re personnel n&rsquo;ont pas \u00e9t\u00e9 collect\u00e9es aupr\u00e8s de la personne concern\u00e9e<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30208\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-15-droit-dacces-de-la-personne-concernee\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 15: Droit d&rsquo;acc\u00e8s de la personne concern\u00e9e<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30209\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-16-droit-de-rectification\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 16: Droit de rectification<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30210\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-17-droit-a-leffacement-droit-a-loubli\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 17: Droit \u00e0 l&rsquo;effacement (\u00abdroit \u00e0 l&rsquo;oubli\u00bb)<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30261\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-18-droit-a-la-limitation-du-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 18: Droit \u00e0 la limitation du traitement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30262\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-19-obligation-de-notification-en-ce-qui-concerne-la-rectification-ou-leffacement-de-donnees-a-caractere-personnel-ou-la-limitation-du-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 19: Obligation de notification en ce qui concerne la rectification ou l&rsquo;effacement de donn\u00e9es \u00e0 caract\u00e8re personnel ou la limitation du traitement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30263\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-20-droit-a-la-portabilite-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 20: Droit \u00e0 la portabilit\u00e9 des donn\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30264\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-21-droit-dopposition\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 21: Droit d&rsquo;opposition<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30265\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-22-decision-individuelle-automatisee-y-compris-le-profilage\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 22: D\u00e9cision individuelle automatis\u00e9e, y compris le profilage<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30266\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-3-droits-de-la-personne-concernee\/article-23-limitations\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 23: Limitations<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30267\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 4: Responsable du traitement et sous-traitant<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30268\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-24-responsabilite-du-responsable-du-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 24: Responsabilit\u00e9 du responsable du traitement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30269\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-25-protection-des-donnees-des-la-conception-et-protection-des-donnees-par-defaut\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 25: Protection des donn\u00e9es d\u00e8s la conception et protection des donn\u00e9es par d\u00e9faut<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30270\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-26-responsables-conjoints-du-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 26: Responsables conjoints du traitement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30271\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-27-representants-des-responsables-du-traitement-ou-des-sous-traitants-qui-ne-sont-pas-etablis-dans-lunion\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 27: Repr\u00e9sentants des responsables du traitement ou des sous-traitants qui ne sont pas \u00e9tablis dans l&rsquo;Union<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30272\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-28-sous-traitant\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 28: Sous-traitant<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30273\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-30-registre-des-activites-de-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 30: Registre des activit\u00e9s de traitement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30274\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-31-cooperation-avec-lautorite-de-controle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 31: Coop\u00e9ration avec l&rsquo;autorit\u00e9 de contr\u00f4le<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30275\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-32-securite-du-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 32: S\u00e9curit\u00e9 du traitement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30276\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-33-notification-a-lautorite-de-controle-dune-violation-de-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 33: Notification \u00e0 l&rsquo;autorit\u00e9 de contr\u00f4le d&rsquo;une violation de donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30277\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-34-communication-a-la-personne-concernee-dune-violation-de-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 34: Communication \u00e0 la personne concern\u00e9e d&rsquo;une violation de donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30278\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-35-analyse-dimpact-relative-a-la-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 35: Analyse d&rsquo;impact relative \u00e0 la protection des donn\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30279\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-36-consultation-prealable\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 36: Consultation pr\u00e9alable<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30280\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-37-designation-du-delegue-a-la-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 37: D\u00e9signation du d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30281\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-38-fonction-du-delegue-a-la-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 38: Fonction du d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30282\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-39-missions-du-delegue-a-la-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 39: Missions du d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30283\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-40-codes-de-conduite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 40: Codes de conduite<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30284\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-41-suivi-des-codes-de-conduite-approuves\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 41: Suivi des codes de conduite approuv\u00e9s<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30285\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-42-certification\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 42: Certification<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30286\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-4-responsable-du-traitement-et-sous-traitant\/article-43-organismes-de-certification\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 43: Organismes de certification<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30287\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 5: Transferts de donn\u00e9es \u00e0 caract\u00e8re personnel vers des pays tiers ou \u00e0 des organisations internationales<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30288\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/article-44-principe-general-applicable-aux-transferts\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 44: Principe g\u00e9n\u00e9ral applicable aux transferts<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30289\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/article-45-transferts-fondes-sur-une-decision-dadequation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 45: Transferts fond\u00e9s sur une d\u00e9cision d&rsquo;ad\u00e9quation<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30290\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/article-46-transferts-moyennant-des-garanties-appropriees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 46: Transferts moyennant des garanties appropri\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30291\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/article-47-regles-dentreprise-contraignantes\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 47: R\u00e8gles d&rsquo;entreprise contraignantes<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30292\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/article-48-transferts-ou-divulgations-non-autorises-par-le-droit-de-lunion\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 48: Transferts ou divulgations non autoris\u00e9s par le droit de l&rsquo;Union<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30293\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/article-49-derogations-pour-des-situations-particulieres\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 49: D\u00e9rogations pour des situations particuli\u00e8res<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30344\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-5-transferts-de-donnees-a-caractere-personnel-vers-des-pays-tiers-ou-a-des-organisations-internationales\/article-50-cooperation-internationale-dans-le-domaine-de-la-protection-des-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 50: Coop\u00e9ration internationale dans le domaine de la protection des donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30345\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 6: Autorit\u00e9s de contr\u00f4le ind\u00e9pendantes<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30346\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-51-autorite-de-controle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 51: Autorit\u00e9 de contr\u00f4le<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30347\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-52-independance\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 52: Ind\u00e9pendance<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30348\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-53-conditions-generales-applicables-aux-membres-de-lautorite-de-controle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 53: Conditions g\u00e9n\u00e9rales applicables aux membres de l&rsquo;autorit\u00e9 de contr\u00f4le<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30349\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-54-regles-relatives-a-letablissement-de-lautorite-de-controle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 54: R\u00e8gles relatives \u00e0 l&rsquo;\u00e9tablissement de l&rsquo;autorit\u00e9 de contr\u00f4le<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30350\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-55-competence\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 55: Comp\u00e9tence<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30351\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-56-competence-de-lautorite-de-controle-chef-de-file\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 56: Comp\u00e9tence de l&rsquo;autorit\u00e9 de contr\u00f4le chef de file<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30352\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-57-missions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 57: Missions<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30353\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-58-pouvoirs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 58: Pouvoirs<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30354\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-6-autorites-de-controle-independantes\/article-59-rapports-dactivite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 59: Rapports d&rsquo;activit\u00e9<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30355\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 7: Coop\u00e9ration et coh\u00e9rence<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30356\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-60-cooperation-entre-lautorite-de-controle-chef-de-file-et-les-autres-autorites-de-controle-concernees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 60: Coop\u00e9ration entre l&rsquo;autorit\u00e9 de contr\u00f4le chef de file et les autres autorit\u00e9s de contr\u00f4le concern\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30357\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-61-assistance-mutuelle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 61: Assistance mutuelle<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30358\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-62-operations-conjointes-des-autorites-de-controle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 62: Op\u00e9rations conjointes des autorit\u00e9s de contr\u00f4le<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30359\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-63-mecanisme-de-controle-de-la-coherence\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 63: M\u00e9canisme de contr\u00f4le de la coh\u00e9rence<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30360\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-64-avis-du-comite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 64: Avis du comit\u00e9<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30411\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-65-reglement-des-litiges-par-le-comite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 65: R\u00e8glement des litiges par le comit\u00e9<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30412\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-66-procedure-durgence\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 66: Proc\u00e9dure d&rsquo;urgence<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30413\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-67-echange-dinformations\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 67: \u00c9change d&rsquo;informations<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30414\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-68-comite-europeen-de-la-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 68: Comit\u00e9 europ\u00e9en de la protection des donn\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30415\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-69-independance\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 69: Ind\u00e9pendance<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30416\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-70-missions-du-comite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 70: Missions du comit\u00e9<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30417\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-71-rapports\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 71: Rapports<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30418\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-72-procedure\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 72: Proc\u00e9dure<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30419\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-73-president\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 73: Pr\u00e9sident<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30420\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-74-missions-du-president\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 74: Missions du pr\u00e9sident<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30421\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-75-secretariat\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 75: Secr\u00e9tariat<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30422\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-7-cooperation-et-coherence\/article-76-confidentialite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 76: Confidentialit\u00e9<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30423\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 8: Voies de recours, responsabilit\u00e9 et sanctions<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30424\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-77-droit-dintroduire-une-reclamation-aupres-dune-autorite-de-controle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 77: Droit d&rsquo;introduire une r\u00e9clamation aupr\u00e8s d&rsquo;une autorit\u00e9 de contr\u00f4le<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30425\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-78-droit-a-un-recours-juridictionnel-effectif-contre-une-autorite-de-controle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 78: Droit \u00e0 un recours juridictionnel effectif contre une autorit\u00e9 de contr\u00f4le<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30426\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-79-droit-a-un-recours-juridictionnel-effectif-contre-un-responsable-du-traitement-ou-un-sous-traitant\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 79: Droit \u00e0 un recours juridictionnel effectif contre un responsable du traitement ou un sous-traitant<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30427\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-80-representation-des-personnes-concernees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 80: Repr\u00e9sentation des personnes concern\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30428\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-81-suspension-dune-action\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 81: Suspension d&rsquo;une action<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30429\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-82-droit-a-reparation-et-responsabilite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 82: Droit \u00e0 r\u00e9paration et responsabilit\u00e9<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30430\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-83-conditions-generales-pour-imposer-des-amendes-administratives\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 83: Conditions g\u00e9n\u00e9rales pour imposer des amendes administratives<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30431\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-8-voies-de-recours-responsabilite-et-sanctions\/article-84-sanctions\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 84: Sanctions<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30432\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 9: Dispositions relatives \u00e0 des situations particuli\u00e8res de traitement<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30433\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/article-85-traitement-et-liberte-dexpression-et-dinformation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 85: Traitement et libert\u00e9 d&rsquo;expression et d&rsquo;information<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30434\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/article-86-traitement-et-acces-du-public-aux-documents-officiels\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 86: Traitement et acc\u00e8s du public aux documents officiels<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30435\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/article-87-traitement-du-numero-didentification-national\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 87: Traitement du num\u00e9ro d&rsquo;identification national<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30436\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/article-88-traitement-de-donnees-dans-le-cadre-des-relations-de-travail\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 88: Traitement de donn\u00e9es dans le cadre des relations de travail<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30437\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/article-89-garanties-et-derogations-applicables-au-traitement-a-des-fins-archivistiques-dans-linteret-public-a-des-fins-de-recherche-scientifique-ou-historique-ou-a-des-fins-statistiques\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 89: Garanties et d\u00e9rogations applicables au traitement \u00e0 des fins archivistiques dans l&rsquo;int\u00e9r\u00eat public, \u00e0 des fins de recherche scientifique ou historique ou \u00e0 des fins statistiques<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30438\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/article-90-obligations-de-secret\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 90: Obligations de secret<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30439\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-9-dispositions-relatives-a-des-situations-particulieres-de-traitement\/article-91-regles-existantes-des-eglises-et-associations-religieuses-en-matiere-de-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 91: R\u00e8gles existantes des \u00e9glises et associations religieuses en mati\u00e8re de protection des donn\u00e9es<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30440\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-10-actes-delegues-et-actes-dexecution\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 10: Actes d\u00e9l\u00e9gu\u00e9s et actes d&rsquo;ex\u00e9cution<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30441\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-10-actes-delegues-et-actes-dexecution\/article-92-exercice-de-la-delegation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 92: Exercice de la d\u00e9l\u00e9gation<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30442\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-10-actes-delegues-et-actes-dexecution\/article-93-comite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 93: Comit\u00e9<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30443\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-11-dispositions-finales\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chapitre 11: Dispositions finales<\/a>\n\t\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30494\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-11-dispositions-finales\/article-94-abrogation-de-la-directive-95-46-ce\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 94: Abrogation de la directive 95\/46\/CE<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30495\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-11-dispositions-finales\/article-95-relation-avec-la-directive-2002-58-ce\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 95: Relation avec la directive 2002\/58\/CE<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30496\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-11-dispositions-finales\/article-96-relation-avec-les-accords-conclus-anterieurement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 96: Relation avec les accords conclus ant\u00e9rieurement<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30497\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-11-dispositions-finales\/article-97-rapports-de-la-commission\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 97: Rapports de la Commission<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30498\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-11-dispositions-finales\/article-98-reexamen-dautres-actes-juridiques-de-lunion-relatifs-a-la-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 98: R\u00e9examen d&rsquo;autres actes juridiques de l&rsquo;Union relatifs \u00e0 la protection des donn\u00e9es<\/a><\/li>\n\t\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30499\"><a href=\"https:\/\/rgpd.com\/fr\/apercu\/chapitre-11-dispositions-finales\/article-99-entree-en-vigueur-et-application\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Article 99: Entr\u00e9e en vigueur et application<\/a><\/li>\n\t\t<\/ul>\n<\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30500\"><a href=\"https:\/\/rgpd.com\/fr\/reglement-sur-lintelligence-artificielle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">R\u00e8glement sur l&rsquo;intelligence artificielle<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30501\"><a href=\"https:\/\/rgpd.com\/fr\/nis2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NIS2<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30976\"><a href=\"https:\/\/rgpd.com\/fr\/guides\/\" class=\"elementor-item\" tabindex=\"-1\">Guides<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30502\"><a href=\"https:\/\/rgpd.com\/fr\/conformite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Conformit\u00e9 au RGPD<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30503\"><a href=\"https:\/\/rgpd.com\/fr\/basiques\/quest-ce-quune-donnee-personnelle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Qu&rsquo;est-ce qu&rsquo;une donn\u00e9e personnelle ?<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30504\"><a href=\"https:\/\/rgpd.com\/fr\/basiques\/200-exemples-de-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">+200 exemples de donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30505\"><a href=\"https:\/\/rgpd.com\/fr\/basiques\/200-exemples-dactivites-de-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">+200 exemples d&rsquo;activit\u00e9s de traitement<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30506\"><a href=\"https:\/\/rgpd.com\/fr\/conformite\/registres-des-activites-de-traitement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Registres des activit\u00e9s de traitement<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30507\"><a href=\"https:\/\/rgpd.com\/fr\/violation-de-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Violation de donn\u00e9es<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30508\"><a href=\"https:\/\/rgpd.com\/fr\/roles-professionnels\/pourquoi-le-rgpd-est-il-important-pour-les-membres-du-conseil-dadministration\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pourquoi le RGPD est-il important pour les membres du conseil d&rsquo;administration ?<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30509\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Liste de contr\u00f4le des exigences du NIS2<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30510\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/politique-de-gestion-des-risques-et-de-securite-des-systemes-dinformation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Politique de gestion des risques et de s\u00e9curit\u00e9 des syst\u00e8mes d&rsquo;information<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30561\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/traitement-des-incidents\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Traitement des incidents<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30562\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/continuite-des-activites\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Continuit\u00e9 des activit\u00e9s<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30563\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/securite-de-la-chaine-dapprovisionnement\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 de la cha\u00eene d&rsquo;approvisionnement<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30564\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/acquisition-developpement-et-maintenance\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Acquisition, d\u00e9veloppement et maintenance<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30565\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/efficacite-des-mesures\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Efficacit\u00e9 des mesures<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30566\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/nis2-formation-a-la-cybersecurite-et-a-la-cyberhygiene\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NIS2 Formation \u00e0 la cybers\u00e9curit\u00e9 et \u00e0 la cyberhygi\u00e8ne<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30567\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/cryptographie\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cryptographie<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30568\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/securite-des-ressources-humaines-politiques-de-controle-dacces-et-gestion-des-actifs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 des ressources humaines, politiques de contr\u00f4le d&rsquo;acc\u00e8s et gestion des actifs<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30569\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/authentification-multifactorielle-et-systemes-de-communication-durgence\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Authentification multifactorielle et syst\u00e8mes de communication d&rsquo;urgence<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30570\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/formation-a-la-gestion-du-nis2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Formation \u00e0 la gestion du NIS2<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30571\"><a href=\"https:\/\/rgpd.com\/fr\/liste-de-controle-des-exigences-du-nis2\/nis2-gouvernance-de-la-cybersecurite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NIS2 Gouvernance de la cybers\u00e9curit\u00e9<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30977\"><a href=\"https:\/\/rgpd.com\/fr\/modeles\/\" class=\"elementor-item\" tabindex=\"-1\">Mod\u00e8les<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30572\"><a href=\"https:\/\/rgpd.com\/fr\/politique-de-confidentialite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Politique de confidentialit\u00e9<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30573\"><a href=\"https:\/\/rgpd.com\/fr\/modeles\/modele-devaluation-des-risques-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mod\u00e8le d&rsquo;\u00e9valuation des risques | RGPD<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-31251\"><a href=\"https:\/\/rgpd.com\/fr\/modeles\/modele-dapr\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mod\u00e8le d&rsquo;APR<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30978\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/\" class=\"elementor-item\" tabindex=\"-1\">Quiz<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-32409\"><a href=\"https:\/\/rgpd.com\/quizzes\/#gdprquiz\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">GDPR<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30574\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test RGPD<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32410\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-dintroduction-au-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test d&rsquo;introduction au RGPD<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32411\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/quest-ce-que-le-test-de-donnees-personnelles\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Qu&rsquo;est-ce que le test de donn\u00e9es personnelles ?<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32412\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/categories-de-donnees-a-caractere-personnel-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cat\u00e9gories de donn\u00e9es \u00e0 caract\u00e8re personnel Test<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32413\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-sur-les-violations-de-donnees-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test sur les violations de donn\u00e9es (RGPD)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32414\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-de-traitement-des-donnees-personnelles\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test de traitement des donn\u00e9es personnelles<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32443\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-sur-les-principes-de-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test sur les principes de protection des donn\u00e9es<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32444\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/bases-legales-test-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bases l\u00e9gales | Test RGPD<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32445\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/droits-des-personnes-concernees-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Droits des personnes concern\u00e9es &#8211; Test<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32446\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/parties-prenantes-et-rgpd-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Parties prenantes et RGPD (Test)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32447\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/rgpd-et-pratiques-de-securite-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">RGPD et pratiques de s\u00e9curit\u00e9 (Test)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32448\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/evaluation-des-risques-lies-au-rgpd-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c9valuation des risques li\u00e9s au RGPD (Test)<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-32449\"><a href=\"https:\/\/rgpd.com\/quizzes\/#cybersecurityquiz\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">Cyber Security<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32450\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/securite-de-linformation-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 de l&rsquo;information (test)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32451\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-nis2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test NIS2<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32452\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-dingenierie-sociale\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test d&rsquo;ing\u00e9nierie sociale<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32453\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/hameconnage-par-courriel-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hame\u00e7onnage par courriel (test)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32454\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/quiz-sur-la-protection-de-la-vie-privee-dans-les-courriels\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Quiz sur la protection de la vie priv\u00e9e dans les courriels<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32455\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/quiz-sur-la-politique-en-matiere-de-courrier-electronique\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Quiz sur la politique en mati\u00e8re de courrier \u00e9lectronique<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32456\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-de-securite-du-mot-de-passe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test de s\u00e9curit\u00e9 du mot de passe<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32457\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-de-securite-de-la-navigation-sur-internet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test de s\u00e9curit\u00e9 de la navigation sur Internet<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32458\"><a href=\"https:\/\/rgpd.com\/fr\/quiz\/test-de-securite-physique\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Test de s\u00e9curit\u00e9 physique<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30575\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/\" class=\"elementor-item\" tabindex=\"-1\">Formation \u00e0 la sensibilisation \u00e0 la s\u00e9curit\u00e9<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30576\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Sensibilisation au RGPD<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30577\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/introduction-au-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Introduction au RGPD<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30578\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/quest-ce-quune-donnee-personnelle\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Qu&rsquo;est-ce qu&rsquo;une donn\u00e9e personnelle ?<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30579\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/categories-de-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cat\u00e9gories de donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30580\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/violations-de-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Violations de donn\u00e9es<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30581\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/traitement-des-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Traitement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30582\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/bases-juridiques-du-traitement-des-donnees-a-caractere-personnel\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bases juridiques du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30583\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/principes-de-protection-des-donnees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Principes de protection des donn\u00e9es<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30584\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/droits-des-personnes-concernees\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Droits des personnes concern\u00e9es<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30585\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/parties-prenantes-et-rgpd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Parties prenantes et RGPD<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30586\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/rgpd-et-pratiques-de-securite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">RGPD et pratiques de s\u00e9curit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30587\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation-au-rgpd\/evaluation-des-risques\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c9valuation des risques<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-30588\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Formation \u00e0 la sensibilisation \u00e0 la s\u00e9curit\u00e9<\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30589\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/securite-de-linformation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 de l&rsquo;information<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30590\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/ingenierie-sociale\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ing\u00e9nierie sociale<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30591\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/courrier-electronique-hameconnage\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Courrier \u00e9lectronique (hame\u00e7onnage)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30592\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/securite-du-mot-de-passe\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 du mot de passe<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30593\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/naviguer-en-toute-securite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Naviguer en toute s\u00e9curit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30632\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/courriel-confidentialite\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Courriel (confidentialit\u00e9)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30633\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/securite-physique\/\" class=\"elementor-sub-item\" tabindex=\"-1\">S\u00e9curit\u00e9 physique<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30634\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/courriel-politiques\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Courriel (politiques)<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30635\"><a href=\"https:\/\/rgpd.com\/fr\/formation-de-sensibilisation\/nis2-introduction\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NIS2 Introduction<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9cec66c e-con-full e-flex e-con e-child\" data-id=\"9cec66c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcf9b29 elementor-widget elementor-widget-template\" data-id=\"dcf9b29\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"149\" class=\"elementor elementor-149\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83ea46e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83ea46e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-184fdee\" data-id=\"184fdee\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cbedbc elementor-widget elementor-widget-sp-breadcrumbs\" data-id=\"7cbedbc\" data-element_type=\"widget\" data-widget_type=\"sp-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav  aria-label=\"breadcrumb\"><ol class=\"breadcrumb\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li class=\"breadcrumb-item active\" aria-current=\"page\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">RGPD.COM<\/span><meta itemprop=\"position\" content=\"1\"><\/li><\/ol><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5306b35 elementor-widget elementor-widget-heading\" data-id=\"5306b35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Article 17<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d90e736 elementor-widget elementor-widget-heading\" data-id=\"d90e736\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Droit \u00e0 l'effacement (\u00abdroit \u00e0 l'oubli\u00bb)<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96499f3 elementor-widget elementor-widget-text-editor\" data-id=\"96499f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"normal\">1. La personne concern\u00e9e a le droit d&rsquo;obtenir du responsable du traitement l&rsquo;effacement, dans les meilleurs d\u00e9lais, de donn\u00e9es \u00e0 caract\u00e8re personnel la concernant et le responsable du traitement a l&rsquo;obligation d&rsquo;effacer ces donn\u00e9es \u00e0 caract\u00e8re personnel dans les meilleurs d\u00e9lais, lorsque l&rsquo;un des motifs suivants s&rsquo;applique:<\/p>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(a)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">les donn\u00e9es \u00e0 caract\u00e8re personnel ne sont plus n\u00e9cessaires au regard des finalit\u00e9s pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es ou trait\u00e9es d&rsquo;une autre mani\u00e8re;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(b)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">la personne concern\u00e9e retire le consentement sur lequel est fond\u00e9 le traitement, conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 1, point a), ou \u00e0 l&rsquo;article 9, paragraphe 2, point a), et il n&rsquo;existe pas d&rsquo;autre fondement juridique au traitement;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(c)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">la personne concern\u00e9e s&rsquo;oppose au traitement en vertu de l&rsquo;article 21, paragraphe 1, et il n&rsquo;existe pas de motif l\u00e9gitime imp\u00e9rieux pour le traitement, ou la personne concern\u00e9e s&rsquo;oppose au traitement en vertu de l&rsquo;article 21, paragraphe 2;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(d)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">les donn\u00e9es \u00e0 caract\u00e8re personnel ont fait l&rsquo;objet d&rsquo;un traitement illicite;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(e)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">les donn\u00e9es \u00e0 caract\u00e8re personnel doivent \u00eatre effac\u00e9es pour respecter une obligation l\u00e9gale qui est pr\u00e9vue par le droit de l&rsquo;Union ou par le droit de l&rsquo;\u00c9tat membre auquel le responsable du traitement est soumis;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(f)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 collect\u00e9es dans le cadre de l&rsquo;offre de services de la soci\u00e9t\u00e9 de l&rsquo;information vis\u00e9e \u00e0 l&rsquo;article 8, paragraphe 1.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"normal\">2. Lorsqu&rsquo;il a rendu publiques les donn\u00e9es \u00e0 caract\u00e8re personnel et qu&rsquo;il est tenu de les effacer en vertu du paragraphe 1, le responsable du traitement, compte tenu des technologies disponibles et des co\u00fbts de mise en \u0153uvre, prend des mesures raisonnables, y compris d&rsquo;ordre technique, pour informer les responsables du traitement qui traitent ces donn\u00e9es \u00e0 caract\u00e8re personnel que la personne concern\u00e9e a demand\u00e9 l&rsquo;effacement par ces responsables du traitement de tout lien vers ces donn\u00e9es \u00e0 caract\u00e8re personnel, ou de toute copie ou reproduction de celles-ci.<\/p>\n<p class=\"normal\">3. Les paragraphes 1 et 2 ne s&rsquo;appliquent pas dans la mesure o\u00f9 ce traitement est n\u00e9cessaire:<\/p>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(a)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">\u00e0 l&rsquo;exercice du droit \u00e0 la libert\u00e9 d&rsquo;expression et d&rsquo;information;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(b)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">pour respecter une obligation l\u00e9gale qui requiert le traitement pr\u00e9vue par le droit de l&rsquo;Union ou par le droit de l&rsquo;\u00c9tat membre auquel le responsable du traitement est soumis, ou pour ex\u00e9cuter une mission d&rsquo;int\u00e9r\u00eat public ou relevant de l&rsquo;exercice de l&rsquo;autorit\u00e9 publique dont est investi le responsable du traitement;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(c)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">pour des motifs d&rsquo;int\u00e9r\u00eat public dans le domaine de la sant\u00e9 publique, conform\u00e9ment \u00e0 l&rsquo;article 9, paragraphe 2, points h) et i), ainsi qu&rsquo;\u00e0 l&rsquo;article 9, paragraphe 3; <\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(d)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">\u00e0 des fins archivistiques dans l&rsquo;int\u00e9r\u00eat public, \u00e0 des fins de recherche scientifique ou historique ou \u00e0 des fins statistiques conform\u00e9ment \u00e0 l&rsquo;article 89, paragraphe 1, dans la mesure o\u00f9 le droit vis\u00e9 au paragraphe 1 est susceptible de rendre impossible ou de compromettre gravement la r\u00e9alisation des objectifs dudit traitement; ou<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"4%\">\n<col width=\"96%\"><\/colgroup>\n<tbody>\n<tr>\n<td valign=\"top\">\n<p class=\"normal\">(e)<\/p>\n<\/td>\n<td valign=\"top\">\n<p class=\"normal\">\u00e0 la constatation, \u00e0 l&rsquo;exercice ou \u00e0 la d\u00e9fense de droits en justice.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-088af6b elementor-widget elementor-widget-heading\" data-id=\"088af6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qu'est-ce que \u00e7a veut dire?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad0b0bc elementor-widget elementor-widget-toggle\" data-id=\"ad0b0bc\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1811\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quand les donn\u00e9es \u00e0 caract\u00e8re personnel doivent-elles \u00eatre supprim\u00e9es \u00e0 la demande d'une personne?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1811\"><h5>Les donn\u00e9es ne sont plus n\u00e9cessaires \u00e0 leur finalit\u00e9 initiale<\/h5>\n<p>Si vous avez collect\u00e9 des donn\u00e9es pour un projet sp\u00e9cifique et que celui-ci est maintenant termin\u00e9, l&rsquo;effacement peut s&rsquo;av\u00e9rer n\u00e9cessaire.<\/p>\n<h5><strong>Le consentement est retir\u00e9<\/strong><\/h5>\n<p>Si le traitement repose uniquement sur le consentement d&rsquo;une personne et que celle-ci change d&rsquo;avis, vous devez effacer les donn\u00e9es, \u00e0 moins qu&rsquo;il n&rsquo;existe une autre base l\u00e9gale.<\/p>\n<h5>Objection l\u00e9gitime sans raison imp\u00e9rieuse<\/h5>\n<p>Si une personne s&rsquo;oppose au traitement de ses donn\u00e9es et que vous ne pouvez pas fournir de raison imp\u00e9rieuse de continuer, vous \u00eates tenu de supprimer ses donn\u00e9es.<\/p>\n<h5>Traitement ill\u00e9gal<\/h5>\n<p>Si vous d\u00e9couvrez que vous avez trait\u00e9 des donn\u00e9es sans base juridique l\u00e9gitime, ces donn\u00e9es doivent \u00eatre supprim\u00e9es.<\/p>\n<h5>Obligation l\u00e9gale<\/h5>\n<p>Vous devez respecter les lois de l&rsquo;UE ou des \u00c9tats membres qui imposent l&rsquo;effacement de certaines donn\u00e9es.<\/p>\n<h5>Donn\u00e9es provenant d&rsquo;enfants offrant des services en ligne<\/h5>\n<p>Des protections sp\u00e9ciales sont en place pour les donn\u00e9es relatives aux enfants, et l&rsquo;effacement peut s&rsquo;av\u00e9rer n\u00e9cessaire dans certaines situations.<\/p>\n<p><!-- notionvc: df72cc65-0711-41ab-a5e6-6357f023840d --><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1812\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1812\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que faire si des donn\u00e9es personnelles ont \u00e9t\u00e9 rendues publiques ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1812\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1812\"><p>Si vous avez publi\u00e9 des donn\u00e9es \u00e0 caract\u00e8re personnel et qu&rsquo;il vous est demand\u00e9 de les effacer, vous devez prendre des mesures raisonnables pour informer les autres organisations qui traitent ces donn\u00e9es de la demande d&rsquo;effacement. Cette proc\u00e9dure doit consister \u00e0 demander la suppression des liens, des copies ou des r\u00e9plications.<!-- notionvc: 36d1e7a6-82dc-4df6-97ee-22db9e494442 --><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1813\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1813\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Existe-t-il des exceptions au droit \u00e0 l'effacement?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1813\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1813\"><p>Oui, il y a des exceptions. L&rsquo;effacement n&rsquo;est pas n\u00e9cessaire lorsque<\/p>\n<ul>\n<li>Elle est contraire au droit \u00e0 la libert\u00e9 d&rsquo;expression et d&rsquo;information.<\/li>\n<li>Le traitement est n\u00e9cessaire pour se conformer \u00e0 une obligation l\u00e9gale ou pour une t\u00e2che d&rsquo;int\u00e9r\u00eat public.<\/li>\n<li>C&rsquo;est n\u00e9cessaire pour des raisons de sant\u00e9 publique (comme indiqu\u00e9 dans le RGPD).<\/li>\n<li>Il s&rsquo;agit d&rsquo;archivage dans l&rsquo;int\u00e9r\u00eat public, de recherche scientifique, historique ou statistique (en vertu de l&rsquo;article 89, paragraphe 1), et l&rsquo;effacement aurait une incidence sur ces objectifs.<\/li>\n<li>Les donn\u00e9es sont essentielles pour les actions en justice.<\/li>\n<\/ul>\n<p><!-- notionvc: c4c2144d-62f9-4d23-988f-7787155975ee --><\/p>\n<p><!-- notionvc: c4c2144d-62f9-4d23-988f-7787155975ee --><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1814\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1814\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quand devez-vous supprimer des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 la suite d'une demande d'effacement?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1814\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1814\"><p>Le RGPD vous oblige \u00e0 supprimer les donn\u00e9es \u00e0 caract\u00e8re personnel sans retard injustifi\u00e9 apr\u00e8s avoir re\u00e7u une demande valide.<!-- notionvc: 3e2e0271-14bd-47bd-9418-6bb0540bd812 --><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1815\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1815\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment respecter efficacement les demandes de suppression dans la pratique?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1815\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1815\"><p>Commencez par \u00e9tablir des proc\u00e9dures internes claires pour traiter les demandes d&rsquo;effacement. Il s&rsquo;agit notamment de v\u00e9rifier l&rsquo;identit\u00e9 de la personne, d&rsquo;\u00e9valuer si la suppression est l\u00e9galement requise et de d\u00e9crire le processus de suppression des donn\u00e9es dans tous les syst\u00e8mes et sauvegardes concern\u00e9s.<\/p>\n<p>Il est essentiel de savoir o\u00f9 votre organisation stocke les donn\u00e9es \u00e0 caract\u00e8re personnel, ce qui constitue une bonne raison de disposer d&rsquo;un registre d\u00e9taill\u00e9 des activit\u00e9s de traitement, comme l&rsquo;exige l&rsquo;article 30. Cela permettra d&rsquo;assurer une suppression compl\u00e8te lorsque des demandes sont re\u00e7ues.<\/p>\n<p>Les outils techniques et l&rsquo;automatisation peuvent constituer un atout majeur, en particulier pour les organisations dont les processus et le stockage des donn\u00e9es sont complexes. Pensez \u00e0 un logiciel qui permet de localiser et d&rsquo;effacer les donn\u00e9es personnelles.<\/p>\n<p>\u00c9tant donn\u00e9 que les sauvegardes sont \u00e9galement importantes, \u00e9laborez une strat\u00e9gie pour traiter les demandes d&rsquo;effacement dans le contexte de vos sauvegardes. Il peut s&rsquo;agir d&rsquo;une suppression personnalis\u00e9e des donn\u00e9es des sauvegardes chaque fois que cela est possible ou d&rsquo;une programmation r\u00e9guli\u00e8re de la suppression compl\u00e8te des sauvegardes apr\u00e8s un d\u00e9lai raisonnable.<\/p>\n<p>Si vous partagez des donn\u00e9es \u00e0 caract\u00e8re personnel avec des tiers, mettez en place un syst\u00e8me permettant de les informer des demandes d&rsquo;effacement et de veiller \u00e0 ce qu&rsquo;ils s&rsquo;y conforment.<\/p>\n<p>Enfin, n&rsquo;oubliez pas de documenter toutes les mesures prises concernant les demandes d&rsquo;effacement. Cela est important pour d\u00e9montrer vos efforts de conformit\u00e9 au RGPD et aide lors du traitement de tout litige potentiel.<\/p>\n<p><!-- notionvc: c335446a-1180-4b49-ada4-68bacdf144b6 --><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Quand les donn\\u00e9es \\u00e0 caract\\u00e8re personnel doivent-elles \\u00eatre supprim\\u00e9es \\u00e0 la demande d'une personne?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<h5>Les donn\\u00e9es ne sont plus n\\u00e9cessaires \\u00e0 leur finalit\\u00e9 initiale<\\\/h5>\\n<p>Si vous avez collect\\u00e9 des donn\\u00e9es pour un projet sp\\u00e9cifique et que celui-ci est maintenant termin\\u00e9, l&rsquo;effacement peut s&rsquo;av\\u00e9rer n\\u00e9cessaire.<\\\/p>\\n<h5><strong>Le consentement est retir\\u00e9<\\\/strong><\\\/h5>\\n<p>Si le traitement repose uniquement sur le consentement d&rsquo;une personne et que celle-ci change d&rsquo;avis, vous devez effacer les donn\\u00e9es, \\u00e0 moins qu&rsquo;il n&rsquo;existe une autre base l\\u00e9gale.<\\\/p>\\n<h5>Objection l\\u00e9gitime sans raison imp\\u00e9rieuse<\\\/h5>\\n<p>Si une personne s&rsquo;oppose au traitement de ses donn\\u00e9es et que vous ne pouvez pas fournir de raison imp\\u00e9rieuse de continuer, vous \\u00eates tenu de supprimer ses donn\\u00e9es.<\\\/p>\\n<h5>Traitement ill\\u00e9gal<\\\/h5>\\n<p>Si vous d\\u00e9couvrez que vous avez trait\\u00e9 des donn\\u00e9es sans base juridique l\\u00e9gitime, ces donn\\u00e9es doivent \\u00eatre supprim\\u00e9es.<\\\/p>\\n<h5>Obligation l\\u00e9gale<\\\/h5>\\n<p>Vous devez respecter les lois de l&rsquo;UE ou des \\u00c9tats membres qui imposent l&rsquo;effacement de certaines donn\\u00e9es.<\\\/p>\\n<h5>Donn\\u00e9es provenant d&rsquo;enfants offrant des services en ligne<\\\/h5>\\n<p>Des protections sp\\u00e9ciales sont en place pour les donn\\u00e9es relatives aux enfants, et l&rsquo;effacement peut s&rsquo;av\\u00e9rer n\\u00e9cessaire dans certaines situations.<\\\/p>\\n<p><!-- notionvc: df72cc65-0711-41ab-a5e6-6357f023840d --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Que faire si des donn\\u00e9es personnelles ont \\u00e9t\\u00e9 rendues publiques ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Si vous avez publi\\u00e9 des donn\\u00e9es \\u00e0 caract\\u00e8re personnel et qu&rsquo;il vous est demand\\u00e9 de les effacer, vous devez prendre des mesures raisonnables pour informer les autres organisations qui traitent ces donn\\u00e9es de la demande d&rsquo;effacement. Cette proc\\u00e9dure doit consister \\u00e0 demander la suppression des liens, des copies ou des r\\u00e9plications.<!-- notionvc: 36d1e7a6-82dc-4df6-97ee-22db9e494442 --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Existe-t-il des exceptions au droit \\u00e0 l'effacement?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Oui, il y a des exceptions. L&rsquo;effacement n&rsquo;est pas n\\u00e9cessaire lorsque<\\\/p>\\n<ul>\\n<li>Elle est contraire au droit \\u00e0 la libert\\u00e9 d&rsquo;expression et d&rsquo;information.<\\\/li>\\n<li>Le traitement est n\\u00e9cessaire pour se conformer \\u00e0 une obligation l\\u00e9gale ou pour une t\\u00e2che d&rsquo;int\\u00e9r\\u00eat public.<\\\/li>\\n<li>C&rsquo;est n\\u00e9cessaire pour des raisons de sant\\u00e9 publique (comme indiqu\\u00e9 dans le RGPD).<\\\/li>\\n<li>Il s&rsquo;agit d&rsquo;archivage dans l&rsquo;int\\u00e9r\\u00eat public, de recherche scientifique, historique ou statistique (en vertu de l&rsquo;article 89, paragraphe 1), et l&rsquo;effacement aurait une incidence sur ces objectifs.<\\\/li>\\n<li>Les donn\\u00e9es sont essentielles pour les actions en justice.<\\\/li>\\n<\\\/ul>\\n<p><!-- notionvc: c4c2144d-62f9-4d23-988f-7787155975ee --><\\\/p>\\n<p><!-- notionvc: c4c2144d-62f9-4d23-988f-7787155975ee --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Quand devez-vous supprimer des donn\\u00e9es \\u00e0 caract\\u00e8re personnel \\u00e0 la suite d'une demande d'effacement?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Le RGPD vous oblige \\u00e0 supprimer les donn\\u00e9es \\u00e0 caract\\u00e8re personnel sans retard injustifi\\u00e9 apr\\u00e8s avoir re\\u00e7u une demande valide.<!-- notionvc: 3e2e0271-14bd-47bd-9418-6bb0540bd812 --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Comment respecter efficacement les demandes de suppression dans la pratique?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Commencez par \\u00e9tablir des proc\\u00e9dures internes claires pour traiter les demandes d&rsquo;effacement. Il s&rsquo;agit notamment de v\\u00e9rifier l&rsquo;identit\\u00e9 de la personne, d&rsquo;\\u00e9valuer si la suppression est l\\u00e9galement requise et de d\\u00e9crire le processus de suppression des donn\\u00e9es dans tous les syst\\u00e8mes et sauvegardes concern\\u00e9s.<\\\/p>\\n<p>Il est essentiel de savoir o\\u00f9 votre organisation stocke les donn\\u00e9es \\u00e0 caract\\u00e8re personnel, ce qui constitue une bonne raison de disposer d&rsquo;un registre d\\u00e9taill\\u00e9 des activit\\u00e9s de traitement, comme l&rsquo;exige l&rsquo;article 30. Cela permettra d&rsquo;assurer une suppression compl\\u00e8te lorsque des demandes sont re\\u00e7ues.<\\\/p>\\n<p>Les outils techniques et l&rsquo;automatisation peuvent constituer un atout majeur, en particulier pour les organisations dont les processus et le stockage des donn\\u00e9es sont complexes. Pensez \\u00e0 un logiciel qui permet de localiser et d&rsquo;effacer les donn\\u00e9es personnelles.<\\\/p>\\n<p>\\u00c9tant donn\\u00e9 que les sauvegardes sont \\u00e9galement importantes, \\u00e9laborez une strat\\u00e9gie pour traiter les demandes d&rsquo;effacement dans le contexte de vos sauvegardes. Il peut s&rsquo;agir d&rsquo;une suppression personnalis\\u00e9e des donn\\u00e9es des sauvegardes chaque fois que cela est possible ou d&rsquo;une programmation r\\u00e9guli\\u00e8re de la suppression compl\\u00e8te des sauvegardes apr\\u00e8s un d\\u00e9lai raisonnable.<\\\/p>\\n<p>Si vous partagez des donn\\u00e9es \\u00e0 caract\\u00e8re personnel avec des tiers, mettez en place un syst\\u00e8me permettant de les informer des demandes d&rsquo;effacement et de veiller \\u00e0 ce qu&rsquo;ils s&rsquo;y conforment.<\\\/p>\\n<p>Enfin, n&rsquo;oubliez pas de documenter toutes les mesures prises concernant les demandes d&rsquo;effacement. Cela est important pour d\\u00e9montrer vos efforts de conformit\\u00e9 au RGPD et aide lors du traitement de tout litige potentiel.<\\\/p>\\n<p><!-- notionvc: c335446a-1180-4b49-ada4-68bacdf144b6 --><\\\/p>\\n\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t<script type=\"application\/ld+json\">\n\t\t\t\t{\n\t\t\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\t\t\"@type\": \"FAQPage\",\n\t\t\t\t\"mainEntity\": [{\"@type\":\"Question\",\"name\":\"Quand les donn\\u00e9es \\u00e0 caract\\u00e8re personnel doivent-elles \\u00eatre supprim\\u00e9es \\u00e0 la demande d'une personne?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<h5>Les donn\\u00e9es ne sont plus n\\u00e9cessaires \\u00e0 leur finalit\\u00e9 initiale<\\\/h5>\\n<p>Si vous avez collect\\u00e9 des donn\\u00e9es pour un projet sp\\u00e9cifique et que celui-ci est maintenant termin\\u00e9, l'effacement peut s'av\\u00e9rer n\\u00e9cessaire.<\\\/p>\\n<h5><strong>Le consentement est retir\\u00e9<\\\/strong><\\\/h5>\\n<p>Si le traitement repose uniquement sur le consentement d'une personne et que celle-ci change d'avis, vous devez effacer les donn\\u00e9es, \\u00e0 moins qu'il n'existe une autre base l\\u00e9gale.<\\\/p>\\n<h5>Objection l\\u00e9gitime sans raison imp\\u00e9rieuse<\\\/h5>\\n<p>Si une personne s'oppose au traitement de ses donn\\u00e9es et que vous ne pouvez pas fournir de raison imp\\u00e9rieuse de continuer, vous \\u00eates tenu de supprimer ses donn\\u00e9es.<\\\/p>\\n<h5>Traitement ill\\u00e9gal<\\\/h5>\\n<p>Si vous d\\u00e9couvrez que vous avez trait\\u00e9 des donn\\u00e9es sans base juridique l\\u00e9gitime, ces donn\\u00e9es doivent \\u00eatre supprim\\u00e9es.<\\\/p>\\n<h5>Obligation l\\u00e9gale<\\\/h5>\\n<p>Vous devez respecter les lois de l'UE ou des \\u00c9tats membres qui imposent l'effacement de certaines donn\\u00e9es.<\\\/p>\\n<h5>Donn\\u00e9es provenant d'enfants offrant des services en ligne<\\\/h5>\\n<p>Des protections sp\\u00e9ciales sont en place pour les donn\\u00e9es relatives aux enfants, et l'effacement peut s'av\\u00e9rer n\\u00e9cessaire dans certaines situations.<\\\/p>\\n<p><!-- notionvc: df72cc65-0711-41ab-a5e6-6357f023840d --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Que faire si des donn\\u00e9es personnelles ont \\u00e9t\\u00e9 rendues publiques ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Si vous avez publi\\u00e9 des donn\\u00e9es \\u00e0 caract\\u00e8re personnel et qu'il vous est demand\\u00e9 de les effacer, vous devez prendre des mesures raisonnables pour informer les autres organisations qui traitent ces donn\\u00e9es de la demande d'effacement. Cette proc\\u00e9dure doit consister \\u00e0 demander la suppression des liens, des copies ou des r\\u00e9plications.<!-- notionvc: 36d1e7a6-82dc-4df6-97ee-22db9e494442 --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Existe-t-il des exceptions au droit \\u00e0 l'effacement?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Oui, il y a des exceptions. L'effacement n'est pas n\\u00e9cessaire lorsque<\\\/p>\\n<ul>\\n<li>Elle est contraire au droit \\u00e0 la libert\\u00e9 d'expression et d'information.<\\\/li>\\n<li>Le traitement est n\\u00e9cessaire pour se conformer \\u00e0 une obligation l\\u00e9gale ou pour une t\\u00e2che d'int\\u00e9r\\u00eat public.<\\\/li>\\n<li>C'est n\\u00e9cessaire pour des raisons de sant\\u00e9 publique (comme indiqu\\u00e9 dans le RGPD).<\\\/li>\\n<li>Il s'agit d'archivage dans l'int\\u00e9r\\u00eat public, de recherche scientifique, historique ou statistique (en vertu de l'article 89, paragraphe 1), et l'effacement aurait une incidence sur ces objectifs.<\\\/li>\\n<li>Les donn\\u00e9es sont essentielles pour les actions en justice.<\\\/li>\\n<\\\/ul>\\n<p><!-- notionvc: c4c2144d-62f9-4d23-988f-7787155975ee --><\\\/p>\\n<p><!-- notionvc: c4c2144d-62f9-4d23-988f-7787155975ee --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Quand devez-vous supprimer des donn\\u00e9es \\u00e0 caract\\u00e8re personnel \\u00e0 la suite d'une demande d'effacement?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Le RGPD vous oblige \\u00e0 supprimer les donn\\u00e9es \\u00e0 caract\\u00e8re personnel sans retard injustifi\\u00e9 apr\\u00e8s avoir re\\u00e7u une demande valide.<!-- notionvc: 3e2e0271-14bd-47bd-9418-6bb0540bd812 --><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Comment respecter efficacement les demandes de suppression dans la pratique?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Commencez par \\u00e9tablir des proc\\u00e9dures internes claires pour traiter les demandes d'effacement. Il s'agit notamment de v\\u00e9rifier l'identit\\u00e9 de la personne, d'\\u00e9valuer si la suppression est l\\u00e9galement requise et de d\\u00e9crire le processus de suppression des donn\\u00e9es dans tous les syst\\u00e8mes et sauvegardes concern\\u00e9s.<\\\/p>\\n<p>Il est essentiel de savoir o\\u00f9 votre organisation stocke les donn\\u00e9es \\u00e0 caract\\u00e8re personnel, ce qui constitue une bonne raison de disposer d'un registre d\\u00e9taill\\u00e9 des activit\\u00e9s de traitement, comme l'exige l'article 30. Cela permettra d'assurer une suppression compl\\u00e8te lorsque des demandes sont re\\u00e7ues.<\\\/p>\\n<p>Les outils techniques et l'automatisation peuvent constituer un atout majeur, en particulier pour les organisations dont les processus et le stockage des donn\\u00e9es sont complexes. Pensez \\u00e0 un logiciel qui permet de localiser et d'effacer les donn\\u00e9es personnelles.<\\\/p>\\n<p>\\u00c9tant donn\\u00e9 que les sauvegardes sont \\u00e9galement importantes, \\u00e9laborez une strat\\u00e9gie pour traiter les demandes d'effacement dans le contexte de vos sauvegardes. Il peut s'agir d'une suppression personnalis\\u00e9e des donn\\u00e9es des sauvegardes chaque fois que cela est possible ou d'une programmation r\\u00e9guli\\u00e8re de la suppression compl\\u00e8te des sauvegardes apr\\u00e8s un d\\u00e9lai raisonnable.<\\\/p>\\n<p>Si vous partagez des donn\\u00e9es \\u00e0 caract\\u00e8re personnel avec des tiers, mettez en place un syst\\u00e8me permettant de les informer des demandes d'effacement et de veiller \\u00e0 ce qu'ils s'y conforment.<\\\/p>\\n<p>Enfin, n'oubliez pas de documenter toutes les mesures prises concernant les demandes d'effacement. Cela est important pour d\\u00e9montrer vos efforts de conformit\\u00e9 au RGPD et aide lors du traitement de tout litige potentiel.<\\\/p>\\n<p><!-- notionvc: c335446a-1180-4b49-ada4-68bacdf144b6 --><\\\/p>\\n\"}}]\n\t\t\t\t}\n\t\t\t<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ca8c3 elementor-widget elementor-widget-template\" data-id=\"53ca8c3\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3333\" class=\"elementor elementor-3333 elementor-136\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-5e71863 e-flex e-con-boxed e-con e-parent\" data-id=\"5e71863\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2b2dfb8 e-con-full e-flex e-con e-child\" data-id=\"2b2dfb8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dffc195 elementor-widget elementor-widget-heading\" data-id=\"dffc195\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Test RGPD<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50690f2 elementor-widget elementor-widget-text-editor\" data-id=\"50690f2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">Voyez si vous connaissez bien le RGPD.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb969e7 e-con-full e-flex e-con e-child\" data-id=\"cb969e7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8eccef6 elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8eccef6\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewBox=\"0 0 384 383.999986\" height=\"512\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"6a72720d93\"><path d=\"M 27 9 L 376 9 L 376 375.710938 L 27 375.710938 Z M 27 9 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><g clip-path=\"url(#6a72720d93)\"><path fill=\"#000000\" d=\"M 78.316406 174.53125 C 111.09375 207.28125 134.507812 240.03125 157.917969 282.136719 C 267.179688 76.28125 399.855469 -17.289062 371.757812 15.460938 C 282.789062 129.304688 221.914062 244.710938 162.601562 375.710938 C 128.261719 313.328125 84.558594 230.671875 31.488281 213.519531 C 15.878906 197.921875 53.339844 160.496094 78.316406 174.53125 Z M 78.316406 174.53125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vous r\u00e9pondrez \u00e0 13 questions sur le RGPD.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewBox=\"0 0 384 383.999986\" height=\"512\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"6a72720d93\"><path d=\"M 27 9 L 376 9 L 376 375.710938 L 27 375.710938 Z M 27 9 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><g clip-path=\"url(#6a72720d93)\"><path fill=\"#000000\" d=\"M 78.316406 174.53125 C 111.09375 207.28125 134.507812 240.03125 157.917969 282.136719 C 267.179688 76.28125 399.855469 -17.289062 371.757812 15.460938 C 282.789062 129.304688 221.914062 244.710938 162.601562 375.710938 C 128.261719 313.328125 84.558594 230.671875 31.488281 213.519531 C 15.878906 197.921875 53.339844 160.496094 78.316406 174.53125 Z M 78.316406 174.53125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cela ne prend que 1 \u00e0 2 minutes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewBox=\"0 0 384 383.999986\" height=\"512\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"6a72720d93\"><path d=\"M 27 9 L 376 9 L 376 375.710938 L 27 375.710938 Z M 27 9 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><g clip-path=\"url(#6a72720d93)\"><path fill=\"#000000\" d=\"M 78.316406 174.53125 C 111.09375 207.28125 134.507812 240.03125 157.917969 282.136719 C 267.179688 76.28125 399.855469 -17.289062 371.757812 15.460938 C 282.789062 129.304688 221.914062 244.710938 162.601562 375.710938 C 128.261719 313.328125 84.558594 230.671875 31.488281 213.519531 C 15.878906 197.921875 53.339844 160.496094 78.316406 174.53125 Z M 78.316406 174.53125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Les experts r\u00e9pondent g\u00e9n\u00e9ralement correctement aux 13 questions.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b99f14 e-con-full e-flex e-con e-child\" data-id=\"9b99f14\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e16ba1e elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"e16ba1e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rgpd.com\/fr\/test-rgpd\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9but du test<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5876bc elementor-widget elementor-widget-template\" data-id=\"f5876bc\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"481\" class=\"elementor elementor-481\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0728292 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0728292\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10e721af\" data-id=\"10e721af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9cc0dbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cc0dbb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d0e392\" data-id=\"5d0e392\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a2969e elementor-widget elementor-widget-heading\" data-id=\"6a2969e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Discover<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-378d68a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"378d68a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Resources<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-23ce1b5\" data-id=\"23ce1b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d99e61 elementor-widget elementor-widget-heading\" data-id=\"5d99e61\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">About<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e4643 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"27e4643\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:%20mail@rgpd.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contact<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Article 17 Droit \u00e0 l&rsquo;effacement (\u00abdroit \u00e0 l&rsquo;oubli\u00bb) 1. La personne concern\u00e9e a le droit d&rsquo;obtenir du responsable du traitement l&rsquo;effacement, dans les meilleurs d\u00e9lais, de donn\u00e9es \u00e0 caract\u00e8re personnel la concernant et le responsable du traitement a l&rsquo;obligation d&rsquo;effacer ces donn\u00e9es \u00e0 caract\u00e8re personnel dans les meilleurs d\u00e9lais, lorsque l&rsquo;un des motifs suivants s&rsquo;applique: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1955,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-2019","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/2019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/comments?post=2019"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/2019\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/pages\/1955"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/fr\/wp-json\/wp\/v2\/media?parent=2019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}