{"id":20100,"date":"2025-03-05T14:10:42","date_gmt":"2025-03-05T14:10:42","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-58\/"},"modified":"2025-03-05T14:18:51","modified_gmt":"2025-03-05T14:18:51","slug":"considerando-58","status":"publish","type":"page","link":"https:\/\/rgpd.com\/pt-pt\/regulamento-inteligencia-artificial\/preambulo\/considerando-58\/","title":{"rendered":"Considerando 58"},"content":{"rendered":"<p class=\"oj-normal\">Outro dom\u00ednio no qual a\u00a0utiliza\u00e7\u00e3o de sistemas de IA merece especial aten\u00e7\u00e3o \u00e9\u00a0o acesso a\u00a0determinados servi\u00e7os e\u00a0presta\u00e7\u00f5es essenciais, de cariz privado e\u00a0p\u00fablico, e\u00a0o usufruto dos mesmos, os quais s\u00e3o necess\u00e1rios para que as pessoas participem plenamente na sociedade ou melhorem o\u00a0seu n\u00edvel de vida. Em especial, as pessoas singulares que se candidatam a\u00a0receber ou que recebem presta\u00e7\u00f5es e\u00a0servi\u00e7os de assist\u00eancia p\u00fablica essenciais de autoridades p\u00fablicas, nomeadamente servi\u00e7os de cuidados de sa\u00fade, presta\u00e7\u00f5es de seguran\u00e7a social, servi\u00e7os sociais que prestam prote\u00e7\u00e3o em casos como maternidade, doen\u00e7a, acidentes de trabalho, depend\u00eancia ou velhice e\u00a0perda de emprego e\u00a0assist\u00eancia social e\u00a0de habita\u00e7\u00e3o, dependem normalmente dessas presta\u00e7\u00f5es e\u00a0servi\u00e7os e\u00a0est\u00e3o numa posi\u00e7\u00e3o vulner\u00e1vel face \u00e0s autoridades respons\u00e1veis. Caso sejam utilizados para determinar a\u00a0concess\u00e3o, recusa, redu\u00e7\u00e3o, revoga\u00e7\u00e3o ou recupera\u00e7\u00e3o dessas presta\u00e7\u00f5es e\u00a0servi\u00e7os pelas autoridades, nomeadamente para determinar se os benefici\u00e1rios t\u00eam leg\u00edtimo direito a\u00a0essas presta\u00e7\u00f5es ou servi\u00e7os, os sistemas de IA podem ter um impacto significativo na subsist\u00eancia das pessoas e\u00a0podem violar os seus direitos fundamentais, como o\u00a0direito \u00e0\u00a0prote\u00e7\u00e3o social, \u00e0\u00a0n\u00e3o discrimina\u00e7\u00e3o, \u00e0\u00a0dignidade do ser humano ou \u00e0\u00a0a\u00e7\u00e3o, pelo que dever\u00e3o ser classificados como sendo de risco elevado. No entanto, o\u00a0presente regulamento n\u00e3o dever\u00e1 constituir um obst\u00e1culo ao desenvolvimento e\u00a0\u00e0 utiliza\u00e7\u00e3o de abordagens inovadoras na administra\u00e7\u00e3o p\u00fablica, que tirariam partido de uma maior utiliza\u00e7\u00e3o de sistemas de IA conformes e\u00a0seguros, desde que esses sistemas n\u00e3o acarretem um risco elevado para as pessoas coletivas e\u00a0singulares. Al\u00e9m disso, os sistemas de IA utilizados para avaliar a\u00a0classifica\u00e7\u00e3o de cr\u00e9dito ou a\u00a0solvabilidade de pessoas singulares dever\u00e3o ser classificados como sistemas de IA de risco elevado, uma vez que determinam o\u00a0acesso dessas pessoas a\u00a0recursos financeiros ou a\u00a0servi\u00e7os essenciais, como o\u00a0alojamento, a\u00a0eletricidade e\u00a0os servi\u00e7os de telecomunica\u00e7\u00f5es. Os sistemas de IA utilizados para essas finalidades podem conduzir \u00e0\u00a0discrimina\u00e7\u00e3o entre pessoas ou grupos e\u00a0podem perpetuar padr\u00f5es hist\u00f3ricos de discrimina\u00e7\u00e3o, como em raz\u00e3o da origem \u00e9tnica ou racial, do g\u00e9nero, da defici\u00eancia, da idade ou da orienta\u00e7\u00e3o sexual, ou podem criar novas formas de impacto discriminat\u00f3rio. No entanto, os sistemas de IA previstos pelo direito da Uni\u00e3o para efeitos de dete\u00e7\u00e3o de fraudes na oferta de servi\u00e7os financeiros e\u00a0para fins prudenciais com vista a\u00a0calcular os requisitos de capital das institui\u00e7\u00f5es de cr\u00e9dito e\u00a0das seguradoras n\u00e3o dever\u00e3o ser considerados de risco elevado nos termos do presente regulamento. Al\u00e9m disso, os sistemas de IA concebidos com vista a\u00a0serem utilizados para avalia\u00e7\u00e3o dos riscos e\u00a0fixa\u00e7\u00e3o de pre\u00e7os em rela\u00e7\u00e3o a\u00a0pessoas singulares para seguros de sa\u00fade e\u00a0de vida tamb\u00e9m podem ter um impacto significativo na subsist\u00eancia das pessoas e, se n\u00e3o forem devidamente concebidos, desenvolvidos e\u00a0utilizados, podem infringir os seus direitos fundamentais e\u00a0ter consequ\u00eancias graves para a\u00a0vida e\u00a0a sa\u00fade das pessoas, incluindo a\u00a0exclus\u00e3o financeira e\u00a0a discrimina\u00e7\u00e3o. Por \u00faltimo, os sistemas de IA utilizados para avaliar e\u00a0classificar chamadas de emerg\u00eancia efetuadas por pessoas singulares ou para enviar ou estabelecer prioridades no envio de servi\u00e7os de primeira resposta a\u00a0emerg\u00eancias, nomeadamente pela pol\u00edcia, bombeiros e\u00a0assist\u00eancia m\u00e9dica, bem como por sistemas de triagem de doentes para cuidados de sa\u00fade de emerg\u00eancia, tamb\u00e9m dever\u00e3o ser classificados como sendo de risco elevado, uma vez que tomam decis\u00f5es em situa\u00e7\u00f5es bastante cr\u00edticas que afetam a\u00a0vida, a\u00a0sa\u00fade e\u00a0os bens das pessoas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Outro dom\u00ednio no qual a\u00a0utiliza\u00e7\u00e3o de sistemas de IA merece especial aten\u00e7\u00e3o \u00e9\u00a0o acesso a\u00a0determinados servi\u00e7os e\u00a0presta\u00e7\u00f5es essenciais, de cariz privado e\u00a0p\u00fablico, e\u00a0o usufruto dos mesmos, os quais s\u00e3o necess\u00e1rios para que as pessoas participem plenamente na sociedade ou melhorem o\u00a0seu n\u00edvel de vida. Em especial, as pessoas singulares que se candidatam a\u00a0receber ou que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20405,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20100","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=20100"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20100\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20405"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=20100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}