{"id":20118,"date":"2025-03-05T14:10:57","date_gmt":"2025-03-05T14:10:57","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-76\/"},"modified":"2025-03-05T14:19:06","modified_gmt":"2025-03-05T14:19:06","slug":"considerando-76","status":"publish","type":"page","link":"https:\/\/rgpd.com\/pt-pt\/regulamento-inteligencia-artificial\/preambulo\/considerando-76\/","title":{"rendered":"Considerando 76"},"content":{"rendered":"<p class=\"oj-normal\">A ciberseguran\u00e7a desempenha um papel fundamental para garantir que os sistemas de IA sejam resistentes \u00e0s a\u00e7\u00f5es de terceiros mal-intencionados que tentam explorar as vulnerabilidades dos sistemas com o\u00a0objetivo de lhes alterar a\u00a0utiliza\u00e7\u00e3o, o\u00a0comportamento e\u00a0o desempenho ou de por em causa as suas propriedades de seguran\u00e7a. Os ciberataques contra sistemas de IA podem tirar partido de ativos espec\u00edficos de IA, como os conjuntos de dados de treino (por exemplo, contamina\u00e7\u00e3o de dados) ou os modelos treinados (por exemplo, ataques antag\u00f3nicos ou infer\u00eancia de membros), ou explorar vulnerabilidades dos ativos digitais do sistema de IA ou da infraestrutura de tecnologias da informa\u00e7\u00e3o e\u00a0comunica\u00e7\u00e3o (TIC) subjacente. A\u00a0fim de assegurar um n\u00edvel de ciberseguran\u00e7a adequado aos riscos, os prestadores de sistemas de IA de risco elevado dever\u00e3o tomar medidas adequadas, como os controlos de seguran\u00e7a, tendo ainda em devida conta a\u00a0infraestrutura de TIC subjacente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ciberseguran\u00e7a desempenha um papel fundamental para garantir que os sistemas de IA sejam resistentes \u00e0s a\u00e7\u00f5es de terceiros mal-intencionados que tentam explorar as vulnerabilidades dos sistemas com o\u00a0objetivo de lhes alterar a\u00a0utiliza\u00e7\u00e3o, o\u00a0comportamento e\u00a0o desempenho ou de por em causa as suas propriedades de seguran\u00e7a. Os ciberataques contra sistemas de IA podem tirar partido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20405,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20118","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=20118"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20118\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20405"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=20118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}