{"id":20145,"date":"2025-03-05T14:11:24","date_gmt":"2025-03-05T14:11:24","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-103\/"},"modified":"2025-03-05T14:19:36","modified_gmt":"2025-03-05T14:19:36","slug":"considerando-103","status":"publish","type":"page","link":"https:\/\/rgpd.com\/pt-pt\/regulamento-inteligencia-artificial\/preambulo\/considerando-103\/","title":{"rendered":"Considerando 103"},"content":{"rendered":"<p class=\"oj-normal\">Componentes de IA gratuitos e\u00a0de fonte aberta abrangem o\u00a0<span class=\"oj-italic\">software<\/span> e\u00a0os dados, incluindo modelos e\u00a0modelos de IA de finalidade geral, ferramentas, servi\u00e7os ou processos de um sistema de IA. Os componentes de IA gratuitos e\u00a0de fonte aberta podem ser disponibilizados atrav\u00e9s de diferentes canais, nomeadamente o\u00a0seu desenvolvimento em reposit\u00f3rios abertos. Para efeitos do presente regulamento, os componentes de IA disponibilizados por um pre\u00e7o ou convertidos em dinheiro de outra forma, nomeadamente no \u00e2mbito da presta\u00e7\u00e3o de apoio t\u00e9cnico ou de outros servi\u00e7os (inclusive atrav\u00e9s de uma plataforma de <span class=\"oj-italic\">software<\/span>) relacionados com o\u00a0componente de IA, ou a\u00a0utiliza\u00e7\u00e3o de dados pessoais por motivos que n\u00e3o sejam exclusivamente para melhorar a\u00a0seguran\u00e7a, a\u00a0compatibilidade ou a\u00a0interoperabilidade do <span class=\"oj-italic\">software<\/span>, com exce\u00e7\u00e3o das transa\u00e7\u00f5es entre microempresas, n\u00e3o dever\u00e3o beneficiar das exce\u00e7\u00f5es previstas para os componentes de IA gratuitos e\u00a0de fonte aberta. O\u00a0facto de disponibilizar componentes de IA atrav\u00e9s de reposit\u00f3rios abertos n\u00e3o dever\u00e1, por si s\u00f3, constituir uma convers\u00e3o em dinheiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Componentes de IA gratuitos e\u00a0de fonte aberta abrangem o\u00a0software e\u00a0os dados, incluindo modelos e\u00a0modelos de IA de finalidade geral, ferramentas, servi\u00e7os ou processos de um sistema de IA. Os componentes de IA gratuitos e\u00a0de fonte aberta podem ser disponibilizados atrav\u00e9s de diferentes canais, nomeadamente o\u00a0seu desenvolvimento em reposit\u00f3rios abertos. Para efeitos do presente regulamento, os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20405,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20145","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=20145"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20145\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20405"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=20145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}