{"id":20173,"date":"2025-03-05T14:11:35","date_gmt":"2025-03-05T14:11:35","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-131\/"},"modified":"2025-03-05T14:19:51","modified_gmt":"2025-03-05T14:19:51","slug":"considerando-131","status":"publish","type":"page","link":"https:\/\/rgpd.com\/pt-pt\/regulamento-inteligencia-artificial\/preambulo\/considerando-131\/","title":{"rendered":"Considerando 131"},"content":{"rendered":"<p class=\"oj-normal\">Para facilitar o\u00a0trabalho da Comiss\u00e3o e\u00a0dos Estados-Membros no dom\u00ednio da IA, bem como aumentar a\u00a0transpar\u00eancia para o\u00a0p\u00fablico, os prestadores de sistemas de IA de risco elevado que n\u00e3o os relacionados com produtos abrangidos pelo \u00e2mbito da legisla\u00e7\u00e3o de harmoniza\u00e7\u00e3o da Uni\u00e3o em vigor aplic\u00e1vel, bem como os prestadores que consideram que um sistema de IA de risco elevado enumerado nos casos concretos de risco elevado num anexo\u00a0do presente regulamento n\u00e3o \u00e9\u00a0de risco elevado com base numa derroga\u00e7\u00e3o, dever\u00e3o ser obrigados a\u00a0registarem-se a\u00a0si mesmos e\u00a0a registar as informa\u00e7\u00f5es sobre o\u00a0seu sistema de IA de risco elevado numa base de dados da\u00a0UE, a\u00a0criar e\u00a0gerir pela Comiss\u00e3o. Antes de um sistema de IA enumerado nos casos concretos de risco elevado de risco elevado num anexo do presente regulamento, os respons\u00e1veis pela implanta\u00e7\u00e3o de sistemas de IA de risco elevado que sejam autoridades, ag\u00eancias ou organismos p\u00fablicos, dever\u00e3o registar-se nessa base de dados e\u00a0selecionar o\u00a0sistema que tencionam utilizar. Os outros respons\u00e1veis pela implanta\u00e7\u00e3o dever\u00e3o ter o\u00a0direito de o\u00a0fazer voluntariamente. Esta sec\u00e7\u00e3o da base de dados da UE dever\u00e1 ser acess\u00edvel ao p\u00fablico, gratuitamente, e\u00a0as informa\u00e7\u00f5es dever\u00e3o ser facilmente naveg\u00e1veis, compreens\u00edveis e\u00a0leg\u00edveis por m\u00e1quina. A\u00a0base de dados da UE dever\u00e1 tamb\u00e9m ser de f\u00e1cil utiliza\u00e7\u00e3o, por exemplo oferecendo funcionalidades de pesquisa, nomeadamente atrav\u00e9s de palavras-chave, que permitam ao p\u00fablico em geral encontrar informa\u00e7\u00f5es pertinentes a\u00a0apresentar aquando do registo dos sistemas de IA de risco elevado e\u00a0nos tipos de sistemas de IA de risco elevado, estabelecidas num anexo\u00a0do presente regulamento a\u00a0que os sistemas de IA de risco elevado correspondem. Qualquer modifica\u00e7\u00e3o substancial de sistemas de IA de risco elevado tamb\u00e9m dever\u00e1 ser registada na base de dados da\u00a0UE. No caso dos sistemas de IA de risco elevado no dom\u00ednio da aplica\u00e7\u00e3o da lei, da migra\u00e7\u00e3o, do asilo e\u00a0da gest\u00e3o do controlo das fronteiras, as obriga\u00e7\u00f5es de registo dever\u00e3o ser cumpridas numa sec\u00e7\u00e3o n\u00e3o p\u00fablica protegida da base de dados da UE. O\u00a0acesso \u00e0\u00a0sec\u00e7\u00e3o segura n\u00e3o p\u00fablica dever\u00e1 ser estritamente limitado \u00e0\u00a0Comiss\u00e3o e\u00a0\u00e0s autoridades de fiscaliza\u00e7\u00e3o do mercado no que diz respeito \u00e0\u00a0respetiva sec\u00e7\u00e3o nacional dessa base de dados. Os sistemas de IA de risco elevado no dom\u00ednio das infraestruturas cr\u00edticas s\u00f3 dever\u00e3o ser registados a\u00a0n\u00edvel nacional. A\u00a0Comiss\u00e3o dever\u00e1 ser a\u00a0respons\u00e1vel pelo tratamento da base de dados da\u00a0UE, em conformidade com o\u00a0Regulamento\u00a0(UE) 2018\/1725. Para assegurar que a\u00a0base de dados esteja plenamente operacional \u00e0\u00a0data de implanta\u00e7\u00e3o, o\u00a0procedimento para a\u00a0cria\u00e7\u00e3o da base de dados da UE dever\u00e1 incluir o\u00a0desenvolvimento de especifica\u00e7\u00f5es funcionais pela Comiss\u00e3o e\u00a0um relat\u00f3rio de auditoria independente. A\u00a0Comiss\u00e3o dever\u00e1 ter em conta os riscos para a\u00a0ciberseguran\u00e7a e\u00a0os riscos no exerc\u00edcio das suas fun\u00e7\u00f5es de respons\u00e1vel pelo tratamento de dados na base de dados da\u00a0UE. A\u00a0fim de maximizar a\u00a0disponibilidade e\u00a0a utiliza\u00e7\u00e3o da base de dados pelo p\u00fablico, a\u00a0base de dados da UE, incluindo as informa\u00e7\u00f5es disponibilizadas atrav\u00e9s da mesma, dever\u00e1 cumprir os requisitos estabelecidos na Diretiva\u00a0(UE) 2019\/882.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para facilitar o\u00a0trabalho da Comiss\u00e3o e\u00a0dos Estados-Membros no dom\u00ednio da IA, bem como aumentar a\u00a0transpar\u00eancia para o\u00a0p\u00fablico, os prestadores de sistemas de IA de risco elevado que n\u00e3o os relacionados com produtos abrangidos pelo \u00e2mbito da legisla\u00e7\u00e3o de harmoniza\u00e7\u00e3o da Uni\u00e3o em vigor aplic\u00e1vel, bem como os prestadores que consideram que um sistema de IA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20405,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20173","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=20173"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20173\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20405"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=20173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}