{"id":20190,"date":"2025-03-05T14:11:47","date_gmt":"2025-03-05T14:11:47","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-148\/"},"modified":"2025-03-05T14:20:06","modified_gmt":"2025-03-05T14:20:06","slug":"considerando-148","status":"publish","type":"page","link":"https:\/\/rgpd.com\/pt-pt\/regulamento-inteligencia-artificial\/preambulo\/considerando-148\/","title":{"rendered":"Considerando 148"},"content":{"rendered":"<p class=\"oj-normal\">O presente regulamento dever\u00e1 estatuir um modelo de governa\u00e7\u00e3o que permita coordenar e\u00a0apoiar a\u00a0aplica\u00e7\u00e3o do presente regulamento a\u00a0n\u00edvel nacional, bem como criar capacidades a\u00a0n\u00edvel da Uni\u00e3o e\u00a0integrar as partes interessadas no dom\u00ednio da IA. A\u00a0aplica\u00e7\u00e3o e\u00a0execu\u00e7\u00e3o efetivas do presente regulamento exigem um modelo de governa\u00e7\u00e3o que permita coordenar e\u00a0desenvolver conhecimentos especializados centrais a\u00a0n\u00edvel da Uni\u00e3o. O\u00a0Servi\u00e7o para a\u00a0IA foi criado por decis\u00e3o da Comiss\u00e3o\u00a0<a href=\"#ntr45-L_202401689PT.000101-E0045\" id=\"ntc45-L_202401689PT.000101-E0045\">(<span class=\"oj-super oj-note-tag\">45<\/span>)<\/a> e\u00a0tem como miss\u00e3o desenvolver os conhecimentos especializados e\u00a0as capacidades da Uni\u00e3o no dom\u00ednio da IA e\u00a0contribuir para a\u00a0aplica\u00e7\u00e3o da legisla\u00e7\u00e3o da Uni\u00e3o em mat\u00e9ria de IA. Os Estados-Membros dever\u00e3o facilitar o\u00a0desempenho das fun\u00e7\u00f5es do Servi\u00e7o para a\u00a0IA com vista a\u00a0apoiar o\u00a0desenvolvimento dos conhecimentos especializados e\u00a0das capacidades da\u00a0Uni\u00e3o a\u00a0n\u00edvel da Uni\u00e3o e\u00a0a refor\u00e7ar o\u00a0funcionamento do mercado \u00fanico digital. Al\u00e9m disso, dever\u00e1 ser criado um Comit\u00e9 composto por representantes dos Estados-Membros, um painel cient\u00edfico que integre a\u00a0comunidade cient\u00edfica e\u00a0um f\u00f3rum consultivo que permita \u00e0s partes interessadas darem o\u00a0seu contributo para a\u00a0aplica\u00e7\u00e3o do presente regulamento, tanto a\u00a0n\u00edvel da Uni\u00e3o como nacional. O\u00a0desenvolvimento dos conhecimentos especializados e\u00a0das capacidades da Uni\u00e3o dever\u00e3o tamb\u00e9m incluir a\u00a0utiliza\u00e7\u00e3o dos recursos e\u00a0conhecimentos especializados existentes, nomeadamente atrav\u00e9s de sinergias com estruturas criadas no contexto da aplica\u00e7\u00e3o a\u00a0n\u00edvel da Uni\u00e3o de outra lei e\u00a0de sinergias com iniciativas conexas a\u00a0n\u00edvel da Uni\u00e3o, como a\u00a0Empresa Comum para a\u00a0Computa\u00e7\u00e3o Europeia de Alto Desempenho e\u00a0as instala\u00e7\u00f5es de ensaio e\u00a0experimenta\u00e7\u00e3o no dom\u00ednio da IA no \u00e2mbito do Programa Europa Digital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presente regulamento dever\u00e1 estatuir um modelo de governa\u00e7\u00e3o que permita coordenar e\u00a0apoiar a\u00a0aplica\u00e7\u00e3o do presente regulamento a\u00a0n\u00edvel nacional, bem como criar capacidades a\u00a0n\u00edvel da Uni\u00e3o e\u00a0integrar as partes interessadas no dom\u00ednio da IA. A\u00a0aplica\u00e7\u00e3o e\u00a0execu\u00e7\u00e3o efetivas do presente regulamento exigem um modelo de governa\u00e7\u00e3o que permita coordenar e\u00a0desenvolver conhecimentos especializados centrais a\u00a0n\u00edvel da Uni\u00e3o. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20405,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20190","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=20190"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20190\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20405"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=20190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}