{"id":20213,"date":"2025-03-05T14:11:59","date_gmt":"2025-03-05T14:11:59","guid":{"rendered":"https:\/\/rgpd.com\/recitals-ai-act\/considerando-171\/"},"modified":"2025-03-05T14:20:22","modified_gmt":"2025-03-05T14:20:22","slug":"considerando-171","status":"publish","type":"page","link":"https:\/\/rgpd.com\/pt-pt\/regulamento-inteligencia-artificial\/preambulo\/considerando-171\/","title":{"rendered":"Considerando 171"},"content":{"rendered":"<p class=\"oj-normal\">As pessoas afetadas dever\u00e3o ter o\u00a0direito de obter explica\u00e7\u00f5es quando uma decis\u00e3o do respons\u00e1vel pela implanta\u00e7\u00e3o tenha por base principalmente os resultados de determinados sistemas de IA de risco elevado abrangidos pelo \u00e2mbito de aplica\u00e7\u00e3o do presente regulamento, e\u00a0quando essa decis\u00e3o produzir efeitos jur\u00eddicos ou analogamente afetar num grau significativo essas pessoas, de uma forma que considerem ter repercuss\u00f5es negativas na sua sa\u00fade, seguran\u00e7a ou direitos fundamentais. Essas explica\u00e7\u00f5es dever\u00e3o ser claras e\u00a0pertinentes e\u00a0constituir uma base sobre a\u00a0qual as pessoas afetadas possam exercer os seus direitos. O\u00a0direito \u00e0\u00a0obten\u00e7\u00e3o de explica\u00e7\u00f5es n\u00e3o dever\u00e1 aplicar-se \u00e0\u00a0utiliza\u00e7\u00e3o de sistemas de IA para os quais decorram do direito da Uni\u00e3o ou do direito nacional exce\u00e7\u00f5es ou restri\u00e7\u00f5es e\u00a0dever\u00e1 aplicar-se apenas na medida em que n\u00e3o esteja j\u00e1 previsto no direito da Uni\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As pessoas afetadas dever\u00e3o ter o\u00a0direito de obter explica\u00e7\u00f5es quando uma decis\u00e3o do respons\u00e1vel pela implanta\u00e7\u00e3o tenha por base principalmente os resultados de determinados sistemas de IA de risco elevado abrangidos pelo \u00e2mbito de aplica\u00e7\u00e3o do presente regulamento, e\u00a0quando essa decis\u00e3o produzir efeitos jur\u00eddicos ou analogamente afetar num grau significativo essas pessoas, de uma forma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":20405,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-20213","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=20213"}],"version-history":[{"count":0,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20213\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/pages\/20405"}],"wp:attachment":[{"href":"https:\/\/rgpd.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=20213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}